{"id":804,"date":"2024-02-12T14:38:00","date_gmt":"2024-02-12T18:38:00","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=804"},"modified":"2024-02-12T14:38:00","modified_gmt":"2024-02-12T18:38:00","slug":"el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/","title":{"rendered":"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe"},"content":{"rendered":"\n<p>El 1% m\u00e1s rico en&nbsp;<strong>Espa\u00f1a<\/strong>&nbsp;soporta menos impuestos sobre su renta que el 20 % m\u00e1s pobre, seg\u00fan un demoledor&nbsp;informe&nbsp;que evidencia la creciente desigualdad en el pa\u00eds europeo.<\/p>\n\n\n\n<p>El estudio de la Fundaci\u00f3n de Estudios de Econom\u00eda Aplicada (Fedea) revela que&nbsp;<strong>el tipo impositivo medio<\/strong>&nbsp;que soportan los hogares m\u00e1s ricos tributa sobre su renta a un tipo efectivo inferior al del resto de contribuyentes, entre los que figuran el 20 % m\u00e1s pobres.<\/p>\n\n\n\n<p>El tipo efectivo es el resultado del cruce entre\u00a0la cantidad total de impuestos pagada por un hogar y su renta bruta.<\/p>\n\n\n\n<p>De hecho, los datos, de 2021, revelan que&nbsp;<strong>los m\u00e1s pobres destinaron&nbsp;<\/strong>un 28,17 % de su renta a impuestos, mientras que en el otro extremo ese porcentaje era del 23,86 %.<\/p>\n\n\n\n<p>Los datos son un duro golpe de realidad en el pa\u00eds europeo y han motivado varias reacciones entre la clase pol\u00edtica, entre ellas la de la vicepresidenta segunda del gobierno socialista de Pedro S\u00e1nchez y ministra de Trabajo, Yolanda D\u00edaz.<\/p>\n\n\n\n<p>\u201cNo es justo, ni razonable que el 1% m\u00e1s rico pague menos impuestos sobre su renta que el 20% m\u00e1s pobre. Necesitamos avanzar en una fiscalidad m\u00e1s justa para luchar contra la desigualdad. Que quien m\u00e1s tenga, m\u00e1s pague\u201d, escribi\u00f3 en las redes sociales.<\/p>\n\n\n\n<p>Fuente RT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 1% m\u00e1s rico en&nbsp;Espa\u00f1a&nbsp;soporta menos impuestos sobre su renta que el 20 % m\u00e1s pobre, seg\u00fan un demoledor&nbsp;informe&nbsp;que evidencia la creciente desigualdad en el pa\u00eds europeo. El estudio de la Fundaci\u00f3n de Estudios de Econom\u00eda Aplicada (Fedea) revela que&nbsp;el tipo impositivo medio&nbsp;que soportan los hogares m\u00e1s ricos tributa sobre su renta a un tipo&#8230;<\/p>\n","protected":false},"author":4,"featured_media":805,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[404],"class_list":["post-804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-impuestos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"El 1% m\u00e1s rico en&nbsp;Espa\u00f1a&nbsp;soporta menos impuestos sobre su renta que el 20 % m\u00e1s pobre, seg\u00fan un demoledor&nbsp;informe&nbsp;que evidencia la creciente desigualdad en el pa\u00eds europeo. El estudio de la Fundaci\u00f3n de Estudios de Econom\u00eda Aplicada (Fedea) revela que&nbsp;el tipo impositivo medio&nbsp;que soportan los hogares m\u00e1s ricos tributa sobre su renta a un tipo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-12T18:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/02\/65ca2a4ce9ff713a6e3f0d61.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t<meta property=\"og:image:height\" content=\"622\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe\",\"datePublished\":\"2024-02-12T18:38:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/65ca2a4ce9ff713a6e3f0d61.jpg\",\"keywords\":[\"Impuestos\"],\"articleSection\":[\"Internacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/\",\"name\":\"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/65ca2a4ce9ff713a6e3f0d61.jpg\",\"datePublished\":\"2024-02-12T18:38:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/65ca2a4ce9ff713a6e3f0d61.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/65ca2a4ce9ff713a6e3f0d61.jpg\",\"width\":1104,\"height\":622},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/02\\\/12\\\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/","og_locale":"es_ES","og_type":"article","og_title":"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe - Bombazo Informativo","og_description":"El 1% m\u00e1s rico en&nbsp;Espa\u00f1a&nbsp;soporta menos impuestos sobre su renta que el 20 % m\u00e1s pobre, seg\u00fan un demoledor&nbsp;informe&nbsp;que evidencia la creciente desigualdad en el pa\u00eds europeo. El estudio de la Fundaci\u00f3n de Estudios de Econom\u00eda Aplicada (Fedea) revela que&nbsp;el tipo impositivo medio&nbsp;que soportan los hogares m\u00e1s ricos tributa sobre su renta a un tipo...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-02-12T18:38:00+00:00","og_image":[{"width":1104,"height":622,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/02\/65ca2a4ce9ff713a6e3f0d61.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe","datePublished":"2024-02-12T18:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/02\/65ca2a4ce9ff713a6e3f0d61.jpg","keywords":["Impuestos"],"articleSection":["Internacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/","name":"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/02\/65ca2a4ce9ff713a6e3f0d61.jpg","datePublished":"2024-02-12T18:38:00+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/02\/65ca2a4ce9ff713a6e3f0d61.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/02\/65ca2a4ce9ff713a6e3f0d61.jpg","width":1104,"height":622},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/02\/12\/el-20-mas-pobre-de-espana-paga-mas-impuestos-sobre-la-renta-que-el-1-mas-rico-segun-informe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"El 20 % m\u00e1s pobre de Espa\u00f1a paga m\u00e1s impuestos sobre la renta que el 1% m\u00e1s rico, seg\u00fan informe"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/02\/65ca2a4ce9ff713a6e3f0d61.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=804"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/804\/revisions"}],"predecessor-version":[{"id":806,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/804\/revisions\/806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/805"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}