{"id":7423,"date":"2026-05-26T10:41:20","date_gmt":"2026-05-26T14:41:20","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=7423"},"modified":"2026-05-26T10:41:22","modified_gmt":"2026-05-26T14:41:22","slug":"pld-opuesto-a-instalacion-de-puertos-secos-frontera","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/","title":{"rendered":"PLD opuesto a instalaci\u00f3n de puertos secos frontera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Argumenta que el Decreto 166-26 favorece a grandes corporaciones, amenaza el comercio tradicional de las comunidades lim\u00edtrofes y amenaza con desplazar a miles de peque\u00f1os comerciantes dominicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En rueda de prensa, Iv\u00e1n Lorenzo alert\u00f3 que la centralizaci\u00f3n log\u00edstica terminar\u00eda perjudicando la econom\u00eda local y a las medianas y peque\u00f1as empresas que hist\u00f3ricamente han sostenido el intercambio en la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que los reglamentos establecidos en el decreto favorecen injustamente a grandes operadores econ\u00f3micos en lugar de proteger a los comerciantes locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Critic\u00f3 que el Gobierno promueva nuevos proyectos sin resolver problemas actuales y se\u00f1al\u00f3 que infraestructuras previas como el puesto interagencial de Jiman\u00ed se mantienen inoperantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEse tejido econ\u00f3mico constituye una importante econom\u00eda social fronteriza que ha permitido sostener empleos, ingresos y estabilidad en comunidades hist\u00f3ricamente abandonadas por el Estado\u201d, consider\u00f3 Lorenzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su juicio, la iniciativa amenaza el comercio tradicional que, durante d\u00e9cadas, ha servido de sustento para miles de familias fronterizas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que el comercio dom\u00ednico-haitiano no fue construido grandes corporaciones multinacionales ni por \u00e9lites econ\u00f3micas alejadas de la realidad fronteriza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano. Argumenta que el Decreto 166-26 favorece a grandes corporaciones, amenaza el comercio tradicional de las comunidades lim\u00edtrofes y amenaza con desplazar a miles de peque\u00f1os comerciantes dominicanos. En rueda de prensa, Iv\u00e1n&#8230;<\/p>\n","protected":false},"author":4,"featured_media":7424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[24],"tags":[403,3090,38,3089],"class_list":["post-7423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-frontera","tag-instalacion","tag-pld","tag-puertos-secos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PLD opuesto a instalaci\u00f3n de puertos secos frontera - Bombazo Informativo<\/title>\n<meta name=\"description\" content=\"El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLD opuesto a instalaci\u00f3n de puertos secos frontera - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-26T14:41:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T14:41:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2026\/05\/Ivan-Lorenzo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"PLD opuesto a instalaci\u00f3n de puertos secos frontera\",\"datePublished\":\"2026-05-26T14:41:20+00:00\",\"dateModified\":\"2026-05-26T14:41:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/\"},\"wordCount\":224,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Ivan-Lorenzo.jpg\",\"keywords\":[\"Frontera\",\"instalaci\u00f3n\",\"PLD\",\"Puertos secos\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/\",\"name\":\"PLD opuesto a instalaci\u00f3n de puertos secos frontera - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Ivan-Lorenzo.jpg\",\"datePublished\":\"2026-05-26T14:41:20+00:00\",\"dateModified\":\"2026-05-26T14:41:22+00:00\",\"description\":\"El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Ivan-Lorenzo.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Ivan-Lorenzo.jpg\",\"width\":948,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2026\\\/05\\\/26\\\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PLD opuesto a instalaci\u00f3n de puertos secos frontera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cc26e2a0c4af37c9b6facbda57f9dacd.jpg?ver=1783647896\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cc26e2a0c4af37c9b6facbda57f9dacd.jpg?ver=1783647896\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cc26e2a0c4af37c9b6facbda57f9dacd.jpg?ver=1783647896\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PLD opuesto a instalaci\u00f3n de puertos secos frontera - Bombazo Informativo","description":"El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/","og_locale":"es_ES","og_type":"article","og_title":"PLD opuesto a instalaci\u00f3n de puertos secos frontera - Bombazo Informativo","og_description":"El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano.","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/","og_site_name":"Bombazo Informativo","article_published_time":"2026-05-26T14:41:20+00:00","article_modified_time":"2026-05-26T14:41:22+00:00","og_image":[{"width":948,"height":703,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2026\/05\/Ivan-Lorenzo.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"PLD opuesto a instalaci\u00f3n de puertos secos frontera","datePublished":"2026-05-26T14:41:20+00:00","dateModified":"2026-05-26T14:41:22+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/"},"wordCount":224,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2026\/05\/Ivan-Lorenzo.jpg","keywords":["Frontera","instalaci\u00f3n","PLD","Puertos secos"],"articleSection":["Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/","name":"PLD opuesto a instalaci\u00f3n de puertos secos frontera - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2026\/05\/Ivan-Lorenzo.jpg","datePublished":"2026-05-26T14:41:20+00:00","dateModified":"2026-05-26T14:41:22+00:00","description":"El Partido de la Liberaci\u00f3n Dominicana (PLD) rechaz\u00f3 este lunes la instalaci\u00f3n de puertos secos en la frontera impulsada por el Gobierno dominicano.","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2026\/05\/Ivan-Lorenzo.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2026\/05\/Ivan-Lorenzo.jpg","width":948,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2026\/05\/26\/pld-opuesto-a-instalacion-de-puertos-secos-frontera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"PLD opuesto a instalaci\u00f3n de puertos secos frontera"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/cc26e2a0c4af37c9b6facbda57f9dacd.jpg?ver=1783647896","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/cc26e2a0c4af37c9b6facbda57f9dacd.jpg?ver=1783647896","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/cc26e2a0c4af37c9b6facbda57f9dacd.jpg?ver=1783647896","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2026\/05\/Ivan-Lorenzo.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/7423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=7423"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/7423\/revisions"}],"predecessor-version":[{"id":7425,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/7423\/revisions\/7425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/7424"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=7423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=7423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=7423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}