{"id":6697,"date":"2025-12-15T11:56:12","date_gmt":"2025-12-15T15:56:12","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=6697"},"modified":"2025-12-15T11:56:14","modified_gmt":"2025-12-15T15:56:14","slug":"desarrollo-social-superate-inaugura-casa-sombra-monte-grande","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/","title":{"rendered":"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d"},"content":{"rendered":"\n<p>Monte Grande.\u2013\u00a0<strong>La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate<\/strong>\u00a0inaugur\u00f3 el proyecto \u201c<strong>Casa sombra Monte Grande\u201d<\/strong>\u00a0en la provincia\u00a0<strong>Azua<\/strong>, una iniciativa del programa\u00a0<strong>Agricultura Familiar<\/strong>, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0<strong>(FAO)<\/strong>, que permitir\u00e1 aumentar la\u00a0<strong>productividad<\/strong>\u00a0y crear\u00a0<strong>mayores oportunidades sostenibles<\/strong>\u00a0para el\u00a0<strong>desarrollo econ\u00f3mico y social<\/strong>\u00a0de los habitantes de esa localidad sure\u00f1a y de sus zonas aleda\u00f1as.<\/p>\n\n\n\n<p><strong>\u201cCasa sombra Palo de la Garza de Monte Grande\u201d&nbsp;<\/strong>est\u00e1 conformada por&nbsp;<strong>10 mujeres y hombres trabajadores de la agricultura<\/strong>&nbsp;que producen&nbsp;<strong>hortalizas y vegetales de ciclo corto<\/strong>&nbsp;<strong>bajo condiciones controladas<\/strong>. Cada unidad productiva dispone de 633 m\u00b2, lo que en conjunto suma 1,900 m\u00b2 distribuidos en tres estructuras. Actualmente, las parcelas est\u00e1n sembradas de&nbsp;<strong>lechuga rizada, remolacha, apio y aj\u00ed gustoso.<\/strong><\/p>\n\n\n\n<p><strong>Gloria Reyes<\/strong>, titular de la Direcci\u00f3n de Desarrollo Social Sup\u00e9rate, indic\u00f3, al dirigirse a los asistentes a la inauguraci\u00f3n, que dicho proyecto se materializ\u00f3 gracias a las&nbsp;<strong>acciones articuladas<\/strong>&nbsp;entre la&nbsp;<strong>entidad<\/strong>&nbsp;gubernamental que dirige, las instituciones aliadas del&nbsp;<strong>Estado dominicano<\/strong>&nbsp;y el respaldo de&nbsp;<strong>organismos internacionales<\/strong>.<\/p>\n\n\n\n<p><em>\u201cLa inauguraci\u00f3n de esta casa sombra es la primera de muchas acciones de este tipo que estaremos realizando en esta comunidad. Por eso quiero agradecer la colaboraci\u00f3n articulada de las diferentes instituciones del Estado dominicano, organismos internacionales y el compromiso de nuestra instituci\u00f3n, a trav\u00e9s de la direcci\u00f3n de Superaci\u00f3n Econ\u00f3mica, el programa Agricultura Familiar y Familias en Paz que han realizado un trabajo fenomenal\u201d,<\/em>&nbsp;precis\u00f3 la funcionaria.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/presidencia.gob.do\/sites\/default\/files\/inline-images\/Cultivo%20de%20lechuga%20repollada%20verde%20y%20morada%2C%20es%20uno%20de%20los%20resultados%20obtenidos%20gracias%20al%20esfuerzo%20de%20las%20familias%20agricultoras%20y%20las%20entidades%20convergentes%20durante%20este%20proceso.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>En ese orden, Reyes resalt\u00f3 la&nbsp;<strong>satisfacci\u00f3n del presidente Luis Abinader&nbsp;<\/strong>con la iniciativa y los frutos que se obtendr\u00e1n. Agradeci\u00f3 al t\u00e9cnico&nbsp;<strong>Fernando Pe\u00f1a<\/strong>, por su importante labor acompa\u00f1ando a las familias participantes.<\/p>\n\n\n\n<p>De su lado,&nbsp;<strong>Fulvio Ure\u00f1a<\/strong>, asesor ambiental del Instituto Nacional de Recursos Hidr\u00e1ulicos&nbsp;<strong>(Indrhi)<\/strong>, manifest\u00f3 que la inauguraci\u00f3n de la casa sombra es el&nbsp;<strong>ejemplo de que la unidad hace la fuerza<\/strong>.&nbsp;<em>\u201cPorque vi a estas mujeres trabajando, cargando fertilizantes y ayudando a levantar la estructura que hoy vemos\u201d,<\/em>&nbsp;agreg\u00f3.<\/p>\n\n\n\n<p>La agricultora&nbsp;<strong>Johanna Ram\u00edrez<\/strong>&nbsp;agradeci\u00f3 en representaci\u00f3n de las familias beneficiarias la ayuda aportada por la Direcci\u00f3n de Desarrollo Social Sup\u00e9rate y su directora Gloria Reyes:&nbsp;<em>\u201cPorque le han puesto todo el amor para que este sue\u00f1o sea una realidad. Gracias por este apoyo, porque podemos decir que nosotros y nuestras familias tenemos de qu\u00e9 vivir\u201d.<\/em><\/p>\n\n\n\n<p>La bendici\u00f3n de la obra estuvo a cargo del&nbsp;<strong>reverendo padre John Montac<\/strong>&nbsp;del Instituto Polit\u00e9cnico Loyola, y a la misma asistieron la viceministra de Desarrollo Rural del Ministerio de Agricultura,&nbsp;<strong>Miriam Guzm\u00e1n<\/strong>; el viceministro de Fomento a la Agroindustria del Ministerio de Industria, Comercio y Mipymes,&nbsp;<strong>Joaqu\u00edn Gonz\u00e1lez<\/strong>; la gobernadora de la provincia<strong>, Mar\u00eda Minerva Navarro,<\/strong>&nbsp;y el diputado&nbsp;<strong>C\u00e9sar Beltr\u00e9<\/strong>.<\/p>\n\n\n\n<p>Por Desarrollo Social Sup\u00e9rate estuvieron presentes&nbsp;<strong>Miriam Batista<\/strong>, directora de Superaci\u00f3n Econ\u00f3mica, y los encargados del programa Agricultura Familiar y Emprendimiento de Negocios y Educaci\u00f3n Financiera,&nbsp;<strong>Anthony Franco y Massiel Tav\u00e1rez.<\/strong><\/p>\n\n\n\n<p><strong>Casa sombra Palo de la Garza Monte Grande<\/strong><\/p>\n\n\n\n<p>El proyecto tiene aproximadamente&nbsp;<strong>1 a\u00f1o desde su instalaci\u00f3n e intervenci\u00f3n inicial<\/strong>&nbsp;de manos de la Direcci\u00f3n de Desarrollo Social Sup\u00e9rate, incluido el proceso de&nbsp;<strong>capacitaci\u00f3n, levantamiento productivo, estructuras y acompa\u00f1amiento t\u00e9cnico<\/strong>. En funcionamiento tiene ya seis meses y est\u00e1n en el proceso de formalizaci\u00f3n de su&nbsp;<strong>cooperativa, Brisas y Aguas de Monte Grande.<\/strong><\/p>\n\n\n\n<p>En ese per\u00edodo, el grupo de agricultores ha logrado&nbsp;<strong>dos ciclos productivos completos<\/strong>, principalmente de hortalizas de ciclo corto (remolacha, apio, aj\u00edes, tres variedades de lechugas, repollo, sand\u00eda, mel\u00f3n, entre otras hortalizas).<\/p>\n\n\n\n<p>En el programa participan 10 agricultores y agricultoras pertenecientes a las familias Sup\u00e9rate: Tomasina M\u00e9ndez Medina, Bernardo Flores Medina, Isabel Flores Medina, Johanna Ram\u00edrez, Marilandy Torres, Martina D\u00edaz, Gerardo Berig\u00fcete, Michel Berig\u00fcete, Adriano Montilla y Belkis Mej\u00eda.<\/p>\n\n\n\n<p>Los terrenos fueron&nbsp;<strong>adquiridos por el Indrhi y transferidos al Instituto Agrario Dominicano (IAD)<\/strong>, bajo un acuerdo entre ambas instituciones para ser distribuidos a los productores beneficiarios del proyecto.<\/p>\n\n\n\n<p>Casa sombra es un&nbsp;<strong>sistema de producci\u00f3n dentro de la agricultura protegida<\/strong>, donde se regula la cantidad de luz y se asegura mejor calidad de la producci\u00f3n, Por tal raz\u00f3n, es&nbsp;<strong>\u00fatil en zonas de mucha radiaci\u00f3n solar<\/strong>&nbsp;y en localidades con escasas posibilidades de producir hortalizas frescas.<\/p>\n\n\n\n<p>Gracias a la alianza estrat\u00e9gica con la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura se han construido&nbsp;<strong>36 proyectos de casas sombra<\/strong>&nbsp;a nivel nacional, a trav\u00e9s del&nbsp;<strong>programa Agricultura Familiar.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monte Grande.\u2013\u00a0La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate\u00a0inaugur\u00f3 el proyecto \u201cCasa sombra Monte Grande\u201d\u00a0en la provincia\u00a0Azua, una iniciativa del programa\u00a0Agricultura Familiar, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0(FAO), que permitir\u00e1 aumentar la\u00a0productividad\u00a0y crear\u00a0mayores oportunidades sostenibles\u00a0para el\u00a0desarrollo econ\u00f3mico y social\u00a0de los habitantes de esa localidad&#8230;<\/p>\n","protected":false},"author":4,"featured_media":6698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41],"tags":[2863,2862,2683],"class_list":["post-6697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales","tag-casa-sombra","tag-desarrollo-social-superate","tag-monte-grande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d - Bombazo Informativo<\/title>\n<meta name=\"description\" content=\"La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate\u00a0inaugur\u00f3 el proyecto \u201cCasa sombra Monte Grande\u201d\u00a0en la provincia\u00a0Azua, una iniciativa del programa\u00a0Agricultura Familiar, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0(FAO)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate\u00a0inaugur\u00f3 el proyecto \u201cCasa sombra Monte Grande\u201d\u00a0en la provincia\u00a0Azua, una iniciativa del programa\u00a0Agricultura Familiar, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0(FAO)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T15:56:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T15:56:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/12\/Gloria-Reyes-directora-de-Desar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d\",\"datePublished\":\"2025-12-15T15:56:12+00:00\",\"dateModified\":\"2025-12-15T15:56:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/\"},\"wordCount\":846,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gloria-Reyes-directora-de-Desar.jpg\",\"keywords\":[\"Casa Sombra\",\"Desarrollo Social Sup\u00e9rate\",\"Monte grande\"],\"articleSection\":[\"Regionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/\",\"name\":\"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gloria-Reyes-directora-de-Desar.jpg\",\"datePublished\":\"2025-12-15T15:56:12+00:00\",\"dateModified\":\"2025-12-15T15:56:14+00:00\",\"description\":\"La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate\u00a0inaugur\u00f3 el proyecto \u201cCasa sombra Monte Grande\u201d\u00a0en la provincia\u00a0Azua, una iniciativa del programa\u00a0Agricultura Familiar, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0(FAO)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gloria-Reyes-directora-de-Desar.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gloria-Reyes-directora-de-Desar.jpg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/12\\\/15\\\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d - Bombazo Informativo","description":"La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate\u00a0inaugur\u00f3 el proyecto \u201cCasa sombra Monte Grande\u201d\u00a0en la provincia\u00a0Azua, una iniciativa del programa\u00a0Agricultura Familiar, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0(FAO)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/","og_locale":"es_ES","og_type":"article","og_title":"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d - Bombazo Informativo","og_description":"La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate\u00a0inaugur\u00f3 el proyecto \u201cCasa sombra Monte Grande\u201d\u00a0en la provincia\u00a0Azua, una iniciativa del programa\u00a0Agricultura Familiar, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0(FAO)","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/","og_site_name":"Bombazo Informativo","article_published_time":"2025-12-15T15:56:12+00:00","article_modified_time":"2025-12-15T15:56:14+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/12\/Gloria-Reyes-directora-de-Desar.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d","datePublished":"2025-12-15T15:56:12+00:00","dateModified":"2025-12-15T15:56:14+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/"},"wordCount":846,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/12\/Gloria-Reyes-directora-de-Desar.jpg","keywords":["Casa Sombra","Desarrollo Social Sup\u00e9rate","Monte grande"],"articleSection":["Regionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/","name":"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/12\/Gloria-Reyes-directora-de-Desar.jpg","datePublished":"2025-12-15T15:56:12+00:00","dateModified":"2025-12-15T15:56:14+00:00","description":"La Direcci\u00f3n de Desarrollo Social Sup\u00e9rate\u00a0inaugur\u00f3 el proyecto \u201cCasa sombra Monte Grande\u201d\u00a0en la provincia\u00a0Azua, una iniciativa del programa\u00a0Agricultura Familiar, el cual cuenta con el respaldo de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura\u00a0(FAO)","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/12\/Gloria-Reyes-directora-de-Desar.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/12\/Gloria-Reyes-directora-de-Desar.jpg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/12\/15\/desarrollo-social-superate-inaugura-casa-sombra-monte-grande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Desarrollo Social Sup\u00e9rate inaugura \u201cCasa sombra Monte Grande\u201d"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/12\/Gloria-Reyes-directora-de-Desar.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/6697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=6697"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/6697\/revisions"}],"predecessor-version":[{"id":6699,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/6697\/revisions\/6699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/6698"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=6697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=6697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=6697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}