{"id":6131,"date":"2025-08-29T10:19:00","date_gmt":"2025-08-29T14:19:00","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=6131"},"modified":"2025-08-29T14:23:40","modified_gmt":"2025-08-29T18:23:40","slug":"sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/","title":{"rendered":"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos"},"content":{"rendered":"\n<p>Santo Domingo.- La miner\u00eda lider\u00f3 el\u00a0<strong>crecimiento econ\u00f3mico<\/strong>\u00a0de julio con un aumento interanual de\u00a0<strong>21 %<\/strong>, seg\u00fan el\u00a0<strong>\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0<\/strong>(IMAE) del\u00a0<strong>Banco Central,<\/strong>\u00a0lo que refleja la creciente contribuci\u00f3n del sector al\u00a0<strong>dinamismo econ\u00f3mico nacional<\/strong>, impulsado por factores\u00a0<strong>locales e internacionales.\u00a0<\/strong><\/p>\n\n\n\n<p>As\u00ed lo inform\u00f3 el ministro de Energ\u00eda y Minas,&nbsp;<strong>Joel Santos<\/strong>, quien precis\u00f3 que dentro del conjunto de sectores que marcaron la diferencia, la&nbsp;<strong>explotaci\u00f3n de minas y canteras<\/strong>&nbsp;alcanz\u00f3 un aumento interanual de&nbsp;<strong>21 %<\/strong>, seguido por manufactura de&nbsp;<strong>zonas francas<\/strong>&nbsp;(7.1 %),&nbsp;<strong>hoteles, bares y restaurantes<\/strong>&nbsp;(4.4%) y&nbsp;<strong>construcci\u00f3n<\/strong>&nbsp;(3.8 %).&nbsp;<\/p>\n\n\n\n<p>Santos explic\u00f3 que el valor de las&nbsp;<strong>exportaciones de oro se duplic\u00f3,<\/strong>&nbsp;al pasar de&nbsp;<strong>USD 115.92 millones<\/strong>&nbsp;en julio de 2024 a&nbsp;<strong>USD 236.36 millones<\/strong>&nbsp;en julio de 2025, manteniendo su posici\u00f3n de principal producto de exportaci\u00f3n del pa\u00eds.&nbsp;<\/p>\n\n\n\n<p>Precis\u00f3, que ese repunte estuvo sustentado en dos factores: el&nbsp;<strong>precio internacional<\/strong>&nbsp;del oro aument\u00f3 un 39 %, alcanzando un promedio de&nbsp;<strong>USD 3,340<\/strong>&nbsp;por onza, frente a los&nbsp;<strong>USD 2,398<\/strong>&nbsp;del a\u00f1o anterior, y que el volumen de producci\u00f3n de la principal mina de oro del pa\u00eds subi\u00f3 un&nbsp;<strong>32 %<\/strong>, al pasar de&nbsp;<strong>48,368 a 63,763<\/strong>&nbsp;onzas, evidenciando mayor capacidad operativa y expansi\u00f3n en las actividades extractivas.&nbsp;<\/p>\n\n\n\n<p>En torno al&nbsp;<strong>impacto fiscal,<\/strong>&nbsp;el titular de Energ\u00eda y Minas resalt\u00f3 el efecto positivo que tambi\u00e9n se reflej\u00f3 en las finanzas p\u00fablicas: las&nbsp;<strong>recaudaciones mineras<\/strong>&nbsp;tambi\u00e9n se duplicaron, con un crecimiento en julio de&nbsp;<strong>129 % interanual<\/strong>, pasando de&nbsp;<strong>RD 3,376.86 millones a RD 7,717.42 millones.<\/strong>&nbsp;<\/p>\n\n\n\n<p><em>\u201cEstos indicadores reflejan un mayor dinamismo y reactivaci\u00f3n, impulsado por los altos precios del oro y una mayor producci\u00f3n nacional. La miner\u00eda contin\u00faa aportando un flujo destacado de divisas, fortaleciendo las finanzas p\u00fablicas y consolid\u00e1ndose como un pilar estrat\u00e9gico para el desarrollo econ\u00f3mico del pa\u00eds\u201d,<\/em>&nbsp;afirm\u00f3.&nbsp;<\/p>\n\n\n\n<p>El ministro Santos subray\u00f3 que la visi\u00f3n del gobierno del&nbsp;<strong>presidente Luis Abinader<\/strong>&nbsp;es garantizar que este crecimiento se produzca bajo un modelo de miner\u00eda&nbsp;<strong>responsable, sostenible y con beneficios compartidos<\/strong>&nbsp;para toda la sociedad dominicana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- La miner\u00eda lider\u00f3 el\u00a0crecimiento econ\u00f3mico\u00a0de julio con un aumento interanual de\u00a021 %, seg\u00fan el\u00a0\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0(IMAE) del\u00a0Banco Central,\u00a0lo que refleja la creciente contribuci\u00f3n del sector al\u00a0dinamismo econ\u00f3mico nacional, impulsado por factores\u00a0locales e internacionales.\u00a0 As\u00ed lo inform\u00f3 el ministro de Energ\u00eda y Minas,&nbsp;Joel Santos, quien precis\u00f3 que dentro del conjunto de sectores&#8230;<\/p>\n","protected":false},"author":4,"featured_media":6132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[445,509,2682],"class_list":["post-6131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-crecimiento-economico","tag-joel-santos","tag-mineria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos - Bombazo Informativo<\/title>\n<meta name=\"description\" content=\"La miner\u00eda lider\u00f3 el\u00a0crecimiento econ\u00f3mico\u00a0de julio con un aumento interanual de\u00a021 %, seg\u00fan el\u00a0\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0(IMAE) del\u00a0Banco Central.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"La miner\u00eda lider\u00f3 el\u00a0crecimiento econ\u00f3mico\u00a0de julio con un aumento interanual de\u00a021 %, seg\u00fan el\u00a0\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0(IMAE) del\u00a0Banco Central.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-29T14:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T18:23:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/08\/Foto-web_24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos\",\"datePublished\":\"2025-08-29T14:19:00+00:00\",\"dateModified\":\"2025-08-29T18:23:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/\"},\"wordCount\":403,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Foto-web_24.jpg\",\"keywords\":[\"Crecimiento Econ\u00f3mico\",\"Joel Santos\",\"Miner\u00eda\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/\",\"name\":\"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Foto-web_24.jpg\",\"datePublished\":\"2025-08-29T14:19:00+00:00\",\"dateModified\":\"2025-08-29T18:23:40+00:00\",\"description\":\"La miner\u00eda lider\u00f3 el\u00a0crecimiento econ\u00f3mico\u00a0de julio con un aumento interanual de\u00a021 %, seg\u00fan el\u00a0\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0(IMAE) del\u00a0Banco Central.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Foto-web_24.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Foto-web_24.jpg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/08\\\/29\\\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos - Bombazo Informativo","description":"La miner\u00eda lider\u00f3 el\u00a0crecimiento econ\u00f3mico\u00a0de julio con un aumento interanual de\u00a021 %, seg\u00fan el\u00a0\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0(IMAE) del\u00a0Banco Central.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/","og_locale":"es_ES","og_type":"article","og_title":"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos - Bombazo Informativo","og_description":"La miner\u00eda lider\u00f3 el\u00a0crecimiento econ\u00f3mico\u00a0de julio con un aumento interanual de\u00a021 %, seg\u00fan el\u00a0\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0(IMAE) del\u00a0Banco Central.","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/","og_site_name":"Bombazo Informativo","article_published_time":"2025-08-29T14:19:00+00:00","article_modified_time":"2025-08-29T18:23:40+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/08\/Foto-web_24.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos","datePublished":"2025-08-29T14:19:00+00:00","dateModified":"2025-08-29T18:23:40+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/"},"wordCount":403,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/08\/Foto-web_24.jpg","keywords":["Crecimiento Econ\u00f3mico","Joel Santos","Miner\u00eda"],"articleSection":["Econom\u00eda"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/","name":"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/08\/Foto-web_24.jpg","datePublished":"2025-08-29T14:19:00+00:00","dateModified":"2025-08-29T18:23:40+00:00","description":"La miner\u00eda lider\u00f3 el\u00a0crecimiento econ\u00f3mico\u00a0de julio con un aumento interanual de\u00a021 %, seg\u00fan el\u00a0\u00cdndice Mensual de Actividad Econ\u00f3mica\u00a0(IMAE) del\u00a0Banco Central.","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/08\/Foto-web_24.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/08\/Foto-web_24.jpg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/08\/29\/sector-de-la-mineria-lidera-crecimiento-economico-de-julio-con-alza-de-21-resalta-ministro-joel-santos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Sector de la miner\u00eda lidera crecimiento econ\u00f3mico de julio con alza de 21 %, resalta ministro Joel Santos"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/08\/Foto-web_24.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/6131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=6131"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/6131\/revisions"}],"predecessor-version":[{"id":6133,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/6131\/revisions\/6133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/6132"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=6131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=6131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=6131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}