{"id":5399,"date":"2025-06-17T15:06:05","date_gmt":"2025-06-17T19:06:05","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=5399"},"modified":"2025-06-17T15:06:06","modified_gmt":"2025-06-17T19:06:06","slug":"pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/","title":{"rendered":"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto"},"content":{"rendered":"\n<p>El presidente de la C\u00e1mara de Diputados, Alfredo Pacheco, inform\u00f3 hoy que la mayor\u00eda de los legisladores favorece que el proyecto de ley de C\u00f3digo Penal sea aprobado en la presente legislatura, que finaliza el pr\u00f3ximo 26 de julio.<\/p>\n\n\n\n<p>Manifest\u00f3 que las diferentes bancadas partidarias est\u00e1n en la mejor disposici\u00f3n de que en la presente legislatura la Rep\u00fablica Dominicana sea dotada de un nuevo C\u00f3digo Penal acorde con los avances que ha tenido la sociedad.<\/p>\n\n\n\n<p>\u201cYo pienso que la generalidad de nuestros diputados y diputadas, mucho m\u00e1s del 90%, independientemente de cu\u00e1l sea nuestra posici\u00f3n en relaci\u00f3n a temas espec\u00edficos con el C\u00f3digo Penal, est\u00e1 de acuerdo en que se apruebe esta pieza legislativa.<\/p>\n\n\n\n<p>Alfredo Pacheco asegur\u00f3 en el tiempo que tiene como diputado nunca hab\u00eda visto tanto entusiasmo entre los diputados y diputadas para la aprobaci\u00f3n de una pieza como lo hay para la aprobaci\u00f3n del proyecto de ley del C\u00f3digo Penal.<\/p>\n\n\n\n<p>Explic\u00f3 que as\u00ed como lo sugiri\u00f3 la Procuradora General de la Rep\u00fablica, como lo ha pedido Fundaci\u00f3n Institucionalidad y Justicia (Finjus), as\u00ed como otras instituciones, este congreso se abocar\u00e1 en los pr\u00f3ximos d\u00edas a conocer el informe que rendir\u00e1 la comisi\u00f3n bicameral.<\/p>\n\n\n\n<p>Pacheco consider\u00f3 que ya al C\u00f3digo Penal le lleg\u00f3 el tiempo de ser aprobado y de ser hecho Ley, en ese sentido continuar\u00e1n escuchando diferentes sectores de la sociedad.<\/p>\n\n\n\n<p>\u201cTenemos varios expertos trabajando en la pieza conjuntamente con la comisi\u00f3n bicameral, que responsablemente ha estado trabajando intensamente, incluso hasta los fines de semanas\u201d precis\u00f3 Pacheco.<\/p>\n\n\n\n<p>Declaraci\u00f3n jurada de bienes<\/p>\n\n\n\n<p>En otro orden, Alfredo Pacheco aclar\u00f3 ante la opini\u00f3n p\u00fablica que es falsa la informaci\u00f3n de que 133 diputados no hayan presentado su declaraci\u00f3n jurada de bienes ante la C\u00e1mara de Cuentas de la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p>\u201cEsa informaci\u00f3n es falsa de toda falsedad\u201d, se\u00f1al\u00f3. Sin embargo, aclar\u00f3 que hay casi 100 exdiputados que no han cumplido con el requerimiento de la Ley, pero explic\u00f3 que la instituci\u00f3n que preside no tiene alcance para llegar hasta ellos.<\/p>\n\n\n\n<p>En ese sentido manifest\u00f3 que la cantidad de diputados actuales que no han completado su declaraci\u00f3n jurada de bienes, es alrededor de un 15 por ciento de la matr\u00edcula total de legisladores<\/p>\n\n\n\n<p>En ese orden, la C\u00e1mara de Diputados dio un plazo de un mes para que los legisladores que faltan por completar su declaraci\u00f3n jurada de bienes puedan hacerlo o de lo contrario sus salarios ser\u00e1n retenidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la C\u00e1mara de Diputados, Alfredo Pacheco, inform\u00f3 hoy que la mayor\u00eda de los legisladores favorece que el proyecto de ley de C\u00f3digo Penal sea aprobado en la presente legislatura, que finaliza el pr\u00f3ximo 26 de julio. Manifest\u00f3 que las diferentes bancadas partidarias est\u00e1n en la mejor disposici\u00f3n de que en la presente&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20,24],"tags":[712,2392,2393,633,625],"class_list":["post-5399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justicia","category-nacionales","tag-alfredo-pacheco","tag-aprobacion","tag-camara-baja","tag-codigo-penal-dominicano","tag-diputados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"El presidente de la C\u00e1mara de Diputados, Alfredo Pacheco, inform\u00f3 hoy que la mayor\u00eda de los legisladores favorece que el proyecto de ley de C\u00f3digo Penal sea aprobado en la presente legislatura, que finaliza el pr\u00f3ximo 26 de julio. Manifest\u00f3 que las diferentes bancadas partidarias est\u00e1n en la mejor disposici\u00f3n de que en la presente...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-17T19:06:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T19:06:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/06\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto\",\"datePublished\":\"2025-06-17T19:06:05+00:00\",\"dateModified\":\"2025-06-17T19:06:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/\"},\"wordCount\":449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg\",\"keywords\":[\"Alfredo Pacheco\",\"Aprobaci\u00f3n\",\"C\u00e1mara Baja\",\"C\u00f3digo Penal Dominicano\",\"Diputados\"],\"articleSection\":[\"Justicia\",\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/\",\"name\":\"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg\",\"datePublished\":\"2025-06-17T19:06:05+00:00\",\"dateModified\":\"2025-06-17T19:06:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg\",\"width\":770,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/06\\\/17\\\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/","og_locale":"es_ES","og_type":"article","og_title":"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto - Bombazo Informativo","og_description":"El presidente de la C\u00e1mara de Diputados, Alfredo Pacheco, inform\u00f3 hoy que la mayor\u00eda de los legisladores favorece que el proyecto de ley de C\u00f3digo Penal sea aprobado en la presente legislatura, que finaliza el pr\u00f3ximo 26 de julio. Manifest\u00f3 que las diferentes bancadas partidarias est\u00e1n en la mejor disposici\u00f3n de que en la presente...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/","og_site_name":"Bombazo Informativo","article_published_time":"2025-06-17T19:06:05+00:00","article_modified_time":"2025-06-17T19:06:06+00:00","og_image":[{"width":770,"height":540,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/06\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto","datePublished":"2025-06-17T19:06:05+00:00","dateModified":"2025-06-17T19:06:06+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/"},"wordCount":449,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/06\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg","keywords":["Alfredo Pacheco","Aprobaci\u00f3n","C\u00e1mara Baja","C\u00f3digo Penal Dominicano","Diputados"],"articleSection":["Justicia","Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/","name":"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/06\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg","datePublished":"2025-06-17T19:06:05+00:00","dateModified":"2025-06-17T19:06:06+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/06\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/06\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg","width":770,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/06\/17\/pacheco-afirma-mayoria-de-diputados-favorece-codigo-penal-sea-aprobado-antes-de-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Pacheco afirma mayor\u00eda de diputados favorece C\u00f3digo Penal sea aprobado antes de agosto"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/06\/Imagen-de-WhatsApp-2025-06-17-a-las-13.39.04_61251ef4-770x540-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=5399"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5399\/revisions"}],"predecessor-version":[{"id":5401,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5399\/revisions\/5401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/5400"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=5399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=5399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=5399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}