{"id":5178,"date":"2025-05-20T11:07:08","date_gmt":"2025-05-20T15:07:08","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=5178"},"modified":"2025-05-20T11:07:09","modified_gmt":"2025-05-20T15:07:09","slug":"dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/","title":{"rendered":"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Medida podr\u00eda empujar a la informalidad<\/h2>\n\n\n\n<p>A partir de este lunes, la Direcci\u00f3n General de Impuestos Internos (DGII) comenzar\u00e1 a aplicar una retenci\u00f3n del 2% sobre todas las ventas realizadas a trav\u00e9s de tarjetas de cr\u00e9dito y d\u00e9bito, sin importar el tama\u00f1o del negocio.<\/p>\n\n\n\n<p>La medida, contemplada en la Norma General 06-2023 y su regulaci\u00f3n complementaria, forma parte de los recientes cambios en el esquema de retenci\u00f3n del ITBIS.<\/p>\n\n\n\n<p>Esto significa que, desde hoy, cada transacci\u00f3n electr\u00f3nica realizada en un comercio con tarjeta ser\u00e1 autom\u00e1ticamente sujeta a esta deducci\u00f3n por parte del fisco.<\/p>\n\n\n\n<p>Aunque las autoridades justifican la medida como un paso hacia una mayor formalizaci\u00f3n de la econom\u00eda y el combate a la evasi\u00f3n fiscal.<\/p>\n\n\n\n<p>Desde ya la medida de la retenci\u00f3n del dos por ciento comienza a crear preocupaci\u00f3n en sectores productivos, ya que podr\u00eda desincentivar el uso de tarjetas de cr\u00e9dito y debido.<\/p>\n\n\n\n<p>El esquema de retenci\u00f3n del ITBIS dispuestas por la Direcci\u00f3n General de Impuestos Internos (DGII) est\u00e1&nbsp; contennida en el marco de la Norma General 06-2023 y su regulaci\u00f3n complementaria.<\/p>\n\n\n\n<p>Seg\u00fan lo informado a trav\u00e9s de comunicaciones enviadas a los comercios,&nbsp; se aplicar\u00e1 una retenci\u00f3n del 2% sobre las ventas realizadas con tarjetas, procesadas mediante soluciones de pago electr\u00f3nicas.<\/p>\n\n\n\n<p>La medida podr\u00eda afectar de forma significativa a peque\u00f1os y medianos negocios, al reducir su flujo de caja y desincentivar el uso de medios de pago digitales, considerados clave para la formalizaci\u00f3n y modernizaci\u00f3n del comercio.<\/p>\n\n\n\n<p>En ese contexto, representantes del sector apelan a la DGII a repensar esta disposici\u00f3n, considerando su impacto desproporcionado en los segmentos m\u00e1s vulnerables del tejido econ\u00f3mico nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medida podr\u00eda empujar a la informalidad A partir de este lunes, la Direcci\u00f3n General de Impuestos Internos (DGII) comenzar\u00e1 a aplicar una retenci\u00f3n del 2% sobre todas las ventas realizadas a trav\u00e9s de tarjetas de cr\u00e9dito y d\u00e9bito, sin importar el tama\u00f1o del negocio. La medida, contemplada en la Norma General 06-2023 y su regulaci\u00f3n&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[730,2276,1400,2277,979,2275,1006],"class_list":["post-5178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-creditos","tag-debitos","tag-dgii","tag-informalidad","tag-itbis","tag-retencion","tag-tarjetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Medida podr\u00eda empujar a la informalidad A partir de este lunes, la Direcci\u00f3n General de Impuestos Internos (DGII) comenzar\u00e1 a aplicar una retenci\u00f3n del 2% sobre todas las ventas realizadas a trav\u00e9s de tarjetas de cr\u00e9dito y d\u00e9bito, sin importar el tama\u00f1o del negocio. La medida, contemplada en la Norma General 06-2023 y su regulaci\u00f3n...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-20T15:07:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T15:07:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito\",\"datePublished\":\"2025-05-20T15:07:08+00:00\",\"dateModified\":\"2025-05-20T15:07:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg\",\"keywords\":[\"Cr\u00e9ditos\",\"D\u00e9bitos\",\"DGII\",\"Informalidad\",\"ITBIS\",\"Retenci\u00f3n\",\"Tarjetas\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/\",\"name\":\"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg\",\"datePublished\":\"2025-05-20T15:07:08+00:00\",\"dateModified\":\"2025-05-20T15:07:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg\",\"width\":1024,\"height\":690},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/20\\\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/","og_locale":"es_ES","og_type":"article","og_title":"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito - Bombazo Informativo","og_description":"Medida podr\u00eda empujar a la informalidad A partir de este lunes, la Direcci\u00f3n General de Impuestos Internos (DGII) comenzar\u00e1 a aplicar una retenci\u00f3n del 2% sobre todas las ventas realizadas a trav\u00e9s de tarjetas de cr\u00e9dito y d\u00e9bito, sin importar el tama\u00f1o del negocio. La medida, contemplada en la Norma General 06-2023 y su regulaci\u00f3n...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/","og_site_name":"Bombazo Informativo","article_published_time":"2025-05-20T15:07:08+00:00","article_modified_time":"2025-05-20T15:07:09+00:00","og_image":[{"width":1024,"height":690,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito","datePublished":"2025-05-20T15:07:08+00:00","dateModified":"2025-05-20T15:07:09+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg","keywords":["Cr\u00e9ditos","D\u00e9bitos","DGII","Informalidad","ITBIS","Retenci\u00f3n","Tarjetas"],"articleSection":["Econom\u00eda"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/","name":"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg","datePublished":"2025-05-20T15:07:08+00:00","dateModified":"2025-05-20T15:07:09+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg","width":1024,"height":690},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/20\/dgii-retendra-un-2-sobre-ventas-realizadas-con-tarjetas-de-credito-o-debito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"DGII retendr\u00e1 un 2% sobre ventas realizadas con tarjetas de cr\u00e9dito o d\u00e9bito"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/proceso-de-afiliacion-al-estado-de-cuenta-cardnet.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=5178"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5178\/revisions"}],"predecessor-version":[{"id":5179,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5178\/revisions\/5179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/5177"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=5178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=5178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=5178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}