{"id":5053,"date":"2025-05-08T13:35:47","date_gmt":"2025-05-08T17:35:47","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=5053"},"modified":"2025-05-08T13:48:03","modified_gmt":"2025-05-08T17:48:03","slug":"el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/","title":{"rendered":"El nuevo papa es el cardenal estadounidense Robert Prevost"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Se har\u00e1 llamar\u00a0<strong>Le\u00f3n XIV<\/strong><\/h2>\n\n\n\n<p>El nuevo papa ser\u00e1 Robert Prevost de Estados Unidos, el primer pont\u00edfice estadounidense en la historia.<\/p>\n\n\n\n<p><strong>Robert Francis Prevost\u00a0<\/strong>fue elegido como el nuevo papa de la\u00a0<strong>Iglesia Cat\u00f3lica<\/strong>. El norteamericano -con pasado misionero en\u00a0<strong>Per\u00fa<\/strong>&#8211; se har\u00e1 llamar\u00a0<strong>Le\u00f3n XIV.<\/strong>\u00a0El anuncio gener\u00f3 un estallido de j\u00fabilo entre los miles de presentes en la\u00a0<strong>Plaza San Pedro\u00a0<\/strong>del\u00a0<strong>Vaticano<\/strong>, donde se esper\u00f3 con expectativa el anuncio de quien suceder\u00eda al \u00faltimo Pont\u00edfice,\u00a0<strong>Francisco<\/strong>, el argentino\u00a0<strong>Jorge Bergoglio<\/strong>.<\/p>\n\n\n\n<p><strong>Prevost\u00a0<\/strong>era-tras la muerte de\u00a0<strong>Francisco<\/strong>-, el prefecto del\u00a0Dicasterio para los Obispos\u00a0y presidente de la\u00a0Pontificia Comisi\u00f3n para Am\u00e9rica Latina\u00a0desde enero de 2023.\u00a0<strong>Fue nombrado cardenal por el \u00faltimo pont\u00edfice el 30 de septiembre de 2023<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fumata blanca<\/h2>\n\n\n\n<p>Finalmente, la&nbsp;<strong>fumata blanca<\/strong>&nbsp;se hab\u00eda hecho presente en el&nbsp;<strong>Vaticano&nbsp;<\/strong>este jueves de la chimenea instalada en el tejado de la&nbsp;<strong>Capilla Sixtina<\/strong>, se\u00f1al que los 133 cardenales encerrados en su interior hab\u00edan logrado escoger al sucesor del papa Francisco en el segundo d\u00eda del c\u00f3nclave.<\/p>\n\n\n\n<p>Los 1.400 millones de cat\u00f3licos del mundo deber\u00e1n esperar ahora el inminente anuncio \u201cHabemus papam\u201d desde el balc\u00f3n de la bas\u00edlica vaticana de San Pedro y la aparici\u00f3n del 267\u00ba pont\u00edfice de la Iglesia cat\u00f3lica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se har\u00e1 llamar\u00a0Le\u00f3n XIV El nuevo papa ser\u00e1 Robert Prevost de Estados Unidos, el primer pont\u00edfice estadounidense en la historia. Robert Francis Prevost\u00a0fue elegido como el nuevo papa de la\u00a0Iglesia Cat\u00f3lica. El norteamericano -con pasado misionero en\u00a0Per\u00fa&#8211; se har\u00e1 llamar\u00a0Le\u00f3n XIV.\u00a0El anuncio gener\u00f3 un estallido de j\u00fabilo entre los miles de presentes en la\u00a0Plaza San&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[2213,2211,2214,2215],"class_list":["post-5053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-estadounidense","tag-habeus-papam","tag-leon-xiv","tag-papa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El nuevo papa es el cardenal estadounidense Robert Prevost - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo papa es el cardenal estadounidense Robert Prevost - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Se har\u00e1 llamar\u00a0Le\u00f3n XIV El nuevo papa ser\u00e1 Robert Prevost de Estados Unidos, el primer pont\u00edfice estadounidense en la historia. Robert Francis Prevost\u00a0fue elegido como el nuevo papa de la\u00a0Iglesia Cat\u00f3lica. El norteamericano -con pasado misionero en\u00a0Per\u00fa&#8211; se har\u00e1 llamar\u00a0Le\u00f3n XIV.\u00a0El anuncio gener\u00f3 un estallido de j\u00fabilo entre los miles de presentes en la\u00a0Plaza San...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-08T17:35:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T17:48:03+00:00\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"El nuevo papa es el cardenal estadounidense Robert Prevost\",\"datePublished\":\"2025-05-08T17:35:47+00:00\",\"dateModified\":\"2025-05-08T17:48:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/\"},\"wordCount\":237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/QT75LRHSHZBMFI34Z57O4KAZCE.avif\",\"keywords\":[\"Estadounidense\",\"Habeus Papam\",\"Le\u00f3n XIV\",\"Papa\"],\"articleSection\":[\"Internacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/\",\"name\":\"El nuevo papa es el cardenal estadounidense Robert Prevost - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/QT75LRHSHZBMFI34Z57O4KAZCE.avif\",\"datePublished\":\"2025-05-08T17:35:47+00:00\",\"dateModified\":\"2025-05-08T17:48:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/QT75LRHSHZBMFI34Z57O4KAZCE.avif\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/QT75LRHSHZBMFI34Z57O4KAZCE.avif\",\"width\":768,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/05\\\/08\\\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nuevo papa es el cardenal estadounidense Robert Prevost\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nuevo papa es el cardenal estadounidense Robert Prevost - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/","og_locale":"es_ES","og_type":"article","og_title":"El nuevo papa es el cardenal estadounidense Robert Prevost - Bombazo Informativo","og_description":"Se har\u00e1 llamar\u00a0Le\u00f3n XIV El nuevo papa ser\u00e1 Robert Prevost de Estados Unidos, el primer pont\u00edfice estadounidense en la historia. Robert Francis Prevost\u00a0fue elegido como el nuevo papa de la\u00a0Iglesia Cat\u00f3lica. El norteamericano -con pasado misionero en\u00a0Per\u00fa&#8211; se har\u00e1 llamar\u00a0Le\u00f3n XIV.\u00a0El anuncio gener\u00f3 un estallido de j\u00fabilo entre los miles de presentes en la\u00a0Plaza San...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/","og_site_name":"Bombazo Informativo","article_published_time":"2025-05-08T17:35:47+00:00","article_modified_time":"2025-05-08T17:48:03+00:00","author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"El nuevo papa es el cardenal estadounidense Robert Prevost","datePublished":"2025-05-08T17:35:47+00:00","dateModified":"2025-05-08T17:48:03+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/"},"wordCount":237,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/QT75LRHSHZBMFI34Z57O4KAZCE.avif","keywords":["Estadounidense","Habeus Papam","Le\u00f3n XIV","Papa"],"articleSection":["Internacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/","name":"El nuevo papa es el cardenal estadounidense Robert Prevost - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/QT75LRHSHZBMFI34Z57O4KAZCE.avif","datePublished":"2025-05-08T17:35:47+00:00","dateModified":"2025-05-08T17:48:03+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/QT75LRHSHZBMFI34Z57O4KAZCE.avif","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/QT75LRHSHZBMFI34Z57O4KAZCE.avif","width":768,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/05\/08\/el-nuevo-papa-es-el-cardenal-estadounidense-robert-prevost\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"El nuevo papa es el cardenal estadounidense Robert Prevost"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/05\/QT75LRHSHZBMFI34Z57O4KAZCE.avif","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=5053"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5053\/revisions"}],"predecessor-version":[{"id":5058,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/5053\/revisions\/5058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/5059"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=5053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=5053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=5053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}