{"id":4363,"date":"2025-01-24T10:17:44","date_gmt":"2025-01-24T14:17:44","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=4363"},"modified":"2025-01-24T10:17:44","modified_gmt":"2025-01-24T14:17:44","slug":"republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/","title":{"rendered":"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria"},"content":{"rendered":"\n<p><strong>Madrid, Espa\u00f1a.<\/strong>\u00a0-El ministro de Turismo, David Collado, calific\u00f3 como un \u00e9xito total la participaci\u00f3n de Rep\u00fablica Dominicana en la feria tur\u00edstica de FITUR, donde cerr\u00f3 con inversiones de US$6,750 millones, superando considerablemente la del a\u00f1o pasado que fue de US$3,500 millones.<\/p>\n\n\n\n<p>En su ya tradicional desayuno con la prensa en FITUR para pasar balance a los resultados de la participaci\u00f3n del pa\u00eds en es importante feria tur\u00edstica mundial, el ministro Collado desglos\u00f3 lo que representar\u00e1 esa inversi\u00f3n para Rep\u00fablica Dominicana y se lograron.<\/p>\n\n\n\n<p>Dijo que el Banco Popular Dominicano logr\u00f3 concretar acuerdos por US$ 2,500 millones, mientras que el Reservas alcanz\u00f3 los US$2,000 millones.<\/p>\n\n\n\n<p>Inform\u00f3 que el banco BHD cerr\u00f3, tambi\u00e9n, con acuerdos por US$2,000, mientras Proamerica logr\u00f3 otros US$250 millones, en su primera participaci\u00f3n como entidad financiera en esta feria.<\/p>\n\n\n\n<p>El ministro Collado expres\u00f3 que esos US$6,750 millones representar\u00e1n 7,400 nuevas habitaciones, 713,000 turistas, 47,800 empleos y US$477 millones en divisas.<\/p>\n\n\n\n<p>\u00abNuestra participaci\u00f3n en esta feria ha sido un extraordinario \u00e9xito para Rep\u00fablica Dominicana\u00bb, subray\u00f3 Collado.<\/p>\n\n\n\n<p>El ministro de Turismo inform\u00f3, tambi\u00e9n, que en marco de la feria se firmaron acuerdos con importantes l\u00edneas a\u00e9reas, lo que representar 500 mil nuevos asientos para este a\u00f1o, solo en el mercado europeo.<\/p>\n\n\n\n<p>Entre las l\u00edneas a\u00e9reas cit\u00f3 a Iberia, Air Europa, Aerom\u00e9xico y Air Transat, entre otras.<\/p>\n\n\n\n<p>El funcionario indic\u00f3 que este a\u00f1o el principal objetivo del gabinete de turismo ser\u00e1 la conectividad a\u00e9rea.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"286\" height=\"176\" src=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/descarga.jpg\" alt=\"\" class=\"wp-image-4365\" style=\"width:427px;height:auto\"\/><\/figure>\n\n\n\n<p>El desayuno cerr\u00f3 con broche de oro, ya que durante el mismo se recibi\u00f3 la informaci\u00f3n de que el Stand de Rep\u00fablica Dominicana gan\u00f3 el premio de mejor Stand de FITUR 2025. Un reconocimiento que ya hab\u00eda logrado el pa\u00eds en 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, Espa\u00f1a.\u00a0-El ministro de Turismo, David Collado, calific\u00f3 como un \u00e9xito total la participaci\u00f3n de Rep\u00fablica Dominicana en la feria tur\u00edstica de FITUR, donde cerr\u00f3 con inversiones de US$6,750 millones, superando considerablemente la del a\u00f1o pasado que fue de US$3,500 millones. En su ya tradicional desayuno con la prensa en FITUR para pasar balance a&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18,15],"tags":[1962,1955,1956,243],"class_list":["post-4363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-internacionales","tag-feria","tag-fitur-2025","tag-inversiones","tag-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Madrid, Espa\u00f1a.\u00a0-El ministro de Turismo, David Collado, calific\u00f3 como un \u00e9xito total la participaci\u00f3n de Rep\u00fablica Dominicana en la feria tur\u00edstica de FITUR, donde cerr\u00f3 con inversiones de US$6,750 millones, superando considerablemente la del a\u00f1o pasado que fue de US$3,500 millones. En su ya tradicional desayuno con la prensa en FITUR para pasar balance a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-24T14:17:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/Ministro-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria\",\"datePublished\":\"2025-01-24T14:17:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Ministro-1.jpeg\",\"keywords\":[\"Feria\",\"Fitur 2025\",\"Inversiones\",\"Turismo\"],\"articleSection\":[\"Econom\u00eda\",\"Internacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/\",\"name\":\"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Ministro-1.jpeg\",\"datePublished\":\"2025-01-24T14:17:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Ministro-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Ministro-1.jpeg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/24\\\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/","og_locale":"es_ES","og_type":"article","og_title":"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria - Bombazo Informativo","og_description":"Madrid, Espa\u00f1a.\u00a0-El ministro de Turismo, David Collado, calific\u00f3 como un \u00e9xito total la participaci\u00f3n de Rep\u00fablica Dominicana en la feria tur\u00edstica de FITUR, donde cerr\u00f3 con inversiones de US$6,750 millones, superando considerablemente la del a\u00f1o pasado que fue de US$3,500 millones. En su ya tradicional desayuno con la prensa en FITUR para pasar balance a...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/","og_site_name":"Bombazo Informativo","article_published_time":"2025-01-24T14:17:44+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/Ministro-1.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria","datePublished":"2025-01-24T14:17:44+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/Ministro-1.jpeg","keywords":["Feria","Fitur 2025","Inversiones","Turismo"],"articleSection":["Econom\u00eda","Internacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/","name":"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/Ministro-1.jpeg","datePublished":"2025-01-24T14:17:44+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/Ministro-1.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/Ministro-1.jpeg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/24\/republica-dominicana-logra-en-fitur-inversiones-por-mas-6750-millones-de-dolares-gana-mejor-estand-de-la-feria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Rep\u00fablica Dominicana logra en Fitur inversiones por m\u00e1s 6,750 millones de d\u00f3lares; gana mejor estand de la feria"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/Ministro-1.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/4363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4363"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/4363\/revisions"}],"predecessor-version":[{"id":4366,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/4363\/revisions\/4366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/4364"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}