{"id":4333,"date":"2025-01-23T07:28:00","date_gmt":"2025-01-23T11:28:00","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=4333"},"modified":"2025-01-23T09:35:43","modified_gmt":"2025-01-23T13:35:43","slug":"indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/","title":{"rendered":"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones"},"content":{"rendered":"\n<p>Santo Domingo.- El Instituto Dominicano de las Telecomunicaciones&nbsp;<strong>(Indotel)<\/strong>&nbsp;anunci\u00f3 el proceso de compra de un&nbsp;<strong>edificio propio,&nbsp;<\/strong>lo cual le&nbsp;<strong>ahorrar\u00e1 al Estado unos RD 1,540 millones en 10 a\u00f1os<\/strong>. Esto representar\u00e1 mejoras en t\u00e9rminos financieros y administrativos, en la&nbsp;<strong>reducci\u00f3n de gastos<\/strong>, as\u00ed como en la&nbsp;<strong>productividad laboral<\/strong>&nbsp;de los colaboradores.<\/p>\n\n\n\n<p>La compra de la edificaci\u00f3n tuvo una inversi\u00f3n total estimada en&nbsp;<strong>RD 1,777.90 millones<\/strong>, que abarca la&nbsp;<strong>construcci\u00f3n, equipamiento y obras complementarias<\/strong>. Este monto resulta significativamente inferior a los RD 3,317.4 millones que costar\u00eda continuar en el edificio Osiris en los pr\u00f3ximos 10 a\u00f1os, considerando las condiciones actuales de arrendamiento. As\u00ed se ahorrar\u00e1n al Estado dominicano RD 1,540 millones y, adem\u00e1s,&nbsp;<strong>el nuevo edificio ser\u00e1 patrimonio p\u00fablico.<\/strong><\/p>\n\n\n\n<p>La instituci\u00f3n de las telecomunicaciones resalt\u00f3 que la compra eliminar\u00eda el&nbsp;<strong>hacinamiento que est\u00e1n sufriendo los empleados<\/strong>&nbsp;de la instituci\u00f3n y que limita la productividad laboral de los colaboradores.<\/p>\n\n\n\n<p>Actualmente, el Indotel paga anualmente&nbsp;<strong>RD 52,103,153.70 por concepto de alquiler<\/strong>&nbsp;del edificio Osiris, adem\u00e1s de costos adicionales por el uso de parqueos externos, servicios como planta el\u00e9ctrica y otras necesidades operativas. Estas partidas suman un costo significativo que, en los \u00faltimos cinco a\u00f1os, ha ascendido a RD 164,790,649.50 y afecta negativamente las finanzas de la instituci\u00f3n.<\/p>\n\n\n\n<p>El due\u00f1o del inmueble que alberga en la actualidad el Indotel, mediante contrato, lleva 24 a\u00f1os recibiendo aproximadamente 100,000 d\u00f3lares mensuales por concepto de alquiler, m\u00e1s los parqueos, que se pagan por separado.<\/p>\n\n\n\n<p>Debido a la situaci\u00f3n, se realiz\u00f3 un an\u00e1lisis exhaustivo, liderado por su presidente del Consejo Directivo,&nbsp;<strong>Guido G\u00f3mez Mazara<\/strong>, y su equipo administrativo, para evaluar&nbsp;<strong>opciones en mejora de la eficiencia financiera y operativa&nbsp;<\/strong>de la instituci\u00f3n. Como resultado, se propuso la adquisici\u00f3n de un inmueble \u00fanico que centralice las operaciones, reduzca los costos actuales de alquiler y mejore las condiciones laborales del personal.<\/p>\n\n\n\n<p>G\u00f3mez Mazara manifest\u00f3 que el proceso para adquirir el inmueble donde se alojar\u00e1n unos 800 colaboradores del Indotel se har\u00e1&nbsp;<strong>de manera transparente y en beneficio de las finanzas p\u00fablicas.<\/strong><\/p>\n\n\n\n<p><em>\u201cCualquier ciudadano de Rep\u00fablica Dominicana que tenga objeci\u00f3n o presuma procedimientos incorrectos, en un plazo de 30 d\u00edas se puede dirigir al ingeniero Mendoza, a Mar\u00eda Teresa y a la Consultor\u00eda Jur\u00eddica del Indotel, en el inter\u00e9s de que cualquier tipo de preocupaci\u00f3n sea canalizada de la mejor forma posible para garantizar que este proceso sea transparente\u201d,<\/em>&nbsp;enfatiz\u00f3 el titular del Indotel.&nbsp;<\/p>\n\n\n\n<p>En el proceso de la compra del edificio participan los miembros del Comit\u00e9 de Seguimiento:&nbsp;<strong>Carlos Mendoza<\/strong>, presidente del Colegio Dominicano de Ingenieros, Arquitectos y Agrimensores (Codia), junto con las se\u00f1oras&nbsp;<strong>Sina Cabral y Mar\u00eda Teresa Cabrera<\/strong>.<\/p>\n\n\n\n<p>Cabrera salud\u00f3 ser parte del proceso de compra y as\u00ed lo se\u00f1al\u00f3:<em>&nbsp;\u201cDeseo expresar mi participaci\u00f3n de veedur\u00eda en este proceso de adquisici\u00f3n de un bien del Estado. Yo quiero tambi\u00e9n saludar la voluntad manifiesta del equipo del Indotel, encabezado por el doctor Guido G\u00f3mez Mazara, de realizar un proceso de compra transparente, abierto a la observaci\u00f3n de personas externas a la instituci\u00f3n\u201d<\/em>, manifest\u00f3.<\/p>\n\n\n\n<p>A partir de esta publicaci\u00f3n, el Indotel otorgar\u00e1 un&nbsp;<strong>plazo de 30 d\u00edas<\/strong>&nbsp;para que cualquier ciudadano o ciudadana interesado pueda presentar&nbsp;<strong>objeciones o impugnaciones<\/strong>&nbsp;relacionadas con el proceso de compras del edificio. Este mecanismo forma parte del compromiso institucional con&nbsp;<strong>la transparencia y la participaci\u00f3n ciudadana<\/strong>, asegurando que el procedimiento cumpla con los m\u00e1s altos est\u00e1ndares de legalidad.<\/p>\n\n\n\n<p>La nueva adquisici\u00f3n fue anunciada durante una rueda de prensa en el Centro Cultural Indotel, encabezada por el presidente del Consejo Directivo de la referida instituci\u00f3n, Guido G\u00f3mez Mazara. Los detalles de la compra fueron ofrecidos por el viceministro de An\u00e1lisis Econ\u00f3mico y Social del Ministerio de Econom\u00eda, Planificaci\u00f3n y Desarrollo y miembro&nbsp;<em>ex officio<\/em>&nbsp;del Consejo Directivo del Indotel,&nbsp;<strong>Alexis Cruz<\/strong>, y el asesor econ\u00f3mico de la instituci\u00f3n,&nbsp;<strong>Apolinar Veloz<\/strong>.<\/p>\n\n\n\n<p><strong>Especificaciones del edificio<\/strong><\/p>\n\n\n\n<p>El edificio que comprar\u00eda el Indotel, ubicado en la avenida 27 de Febrero, cuenta con&nbsp;<strong>10 pisos<\/strong>, cuatro niveles de parqueos soterrados y un nivel de parqueos en superficie (primer nivel) con una cantidad de 9 parqueos para motocicletas y 99 parqueos para autom\u00f3viles, lo que representa un total de 108 parqueos para veh\u00edculos. Adem\u00e1s, tiene un&nbsp;<strong>dise\u00f1o inclusivo libre de barreras<\/strong>, con accesos adecuados para personas con movilidad reducida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El Instituto Dominicano de las Telecomunicaciones&nbsp;(Indotel)&nbsp;anunci\u00f3 el proceso de compra de un&nbsp;edificio propio,&nbsp;lo cual le&nbsp;ahorrar\u00e1 al Estado unos RD 1,540 millones en 10 a\u00f1os. Esto representar\u00e1 mejoras en t\u00e9rminos financieros y administrativos, en la&nbsp;reducci\u00f3n de gastos, as\u00ed como en la&nbsp;productividad laboral&nbsp;de los colaboradores. La compra de la edificaci\u00f3n tuvo una inversi\u00f3n total estimada&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[1964,1963,1471],"class_list":["post-4333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-compra","tag-edificio","tag-indotel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.- El Instituto Dominicano de las Telecomunicaciones&nbsp;(Indotel)&nbsp;anunci\u00f3 el proceso de compra de un&nbsp;edificio propio,&nbsp;lo cual le&nbsp;ahorrar\u00e1 al Estado unos RD 1,540 millones en 10 a\u00f1os. Esto representar\u00e1 mejoras en t\u00e9rminos financieros y administrativos, en la&nbsp;reducci\u00f3n de gastos, as\u00ed como en la&nbsp;productividad laboral&nbsp;de los colaboradores. La compra de la edificaci\u00f3n tuvo una inversi\u00f3n total estimada...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T11:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T13:35:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones\",\"datePublished\":\"2025-01-23T11:28:00+00:00\",\"dateModified\":\"2025-01-23T13:35:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/\"},\"wordCount\":796,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg\",\"keywords\":[\"Compra\",\"Edificio\",\"INDOTEL\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/\",\"name\":\"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg\",\"datePublished\":\"2025-01-23T11:28:00+00:00\",\"dateModified\":\"2025-01-23T13:35:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg\",\"width\":696,\"height\":392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2025\\\/01\\\/23\\\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/","og_locale":"es_ES","og_type":"article","og_title":"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones - Bombazo Informativo","og_description":"Santo Domingo.- El Instituto Dominicano de las Telecomunicaciones&nbsp;(Indotel)&nbsp;anunci\u00f3 el proceso de compra de un&nbsp;edificio propio,&nbsp;lo cual le&nbsp;ahorrar\u00e1 al Estado unos RD 1,540 millones en 10 a\u00f1os. Esto representar\u00e1 mejoras en t\u00e9rminos financieros y administrativos, en la&nbsp;reducci\u00f3n de gastos, as\u00ed como en la&nbsp;productividad laboral&nbsp;de los colaboradores. La compra de la edificaci\u00f3n tuvo una inversi\u00f3n total estimada...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/","og_site_name":"Bombazo Informativo","article_published_time":"2025-01-23T11:28:00+00:00","article_modified_time":"2025-01-23T13:35:43+00:00","og_image":[{"width":696,"height":392,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones","datePublished":"2025-01-23T11:28:00+00:00","dateModified":"2025-01-23T13:35:43+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/"},"wordCount":796,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg","keywords":["Compra","Edificio","INDOTEL"],"articleSection":["Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/","name":"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg","datePublished":"2025-01-23T11:28:00+00:00","dateModified":"2025-01-23T13:35:43+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg","width":696,"height":392},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2025\/01\/23\/indotel-comprara-edificio-en-la-27-de-febrero-por-rd-1777-90-millones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Indotel comprar\u00e1 edificio en la 27 de Febrero por RD 1,777.90 millones"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2025\/01\/NUEVOEDIFICIOINDOTEL-696x392-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/4333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4333"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/4333\/revisions"}],"predecessor-version":[{"id":4335,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/4333\/revisions\/4335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/4334"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}