{"id":3848,"date":"2024-11-12T14:52:58","date_gmt":"2024-11-12T18:52:58","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=3848"},"modified":"2024-11-12T14:52:58","modified_gmt":"2024-11-12T18:52:58","slug":"cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/","title":{"rendered":"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El general Fr\u00f3meta Herasme destac\u00f3 el gran apoyo recibido de la alcaldesa Carolina Mej\u00eda<\/h2>\n\n\n\n<p>Santo Domingo. &#8211; El Cuerpo de Bomberos del Distrito Nacional realiz\u00f3 466 asistencias durante el mes de octubre, completando un total de 5,206 emergencias asistidas desde inicio de enero hasta finales de octubre.<\/p>\n\n\n\n<p>A lo largo del mes de octubre los bomberos asistieron 128 incendios el\u00e9ctricos, 47 residenciales y 32 comerciales. Asimismo, realizaron 76 investigaciones de incendios, 65 inspecciones a empresas, 61 por escapes de gas, 50 rescates terrestres y se retiraron 42 \u00e1rboles ca\u00eddos.<\/p>\n\n\n\n<p>Adem\u00e1s, asistieron a 22 personas heridas, 22 accidentes de tr\u00e1nsito, 24 incendios vehicular, 29 derrame de combustible, nueve rescates de animales, seis rescates en alturas, cuatro personas fallecidas y un rescate acu\u00e1tico.<\/p>\n\n\n\n<p>Actualmente, los Bomberos del Distrito Nacional promedian 18 salidas diarias para atender emergencias.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.47-PM.jpeg\" alt=\"\" class=\"wp-image-3850\" srcset=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.47-PM.jpeg 1000w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.47-PM-300x200.jpeg 300w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.47-PM-768x512.jpeg 768w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.47-PM-600x400.jpeg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>Apoyo de la alcaldesa<\/p>\n\n\n\n<p>El intendente del Cuerpo de Bomberos del DN, general Jos\u00e9 Luis Fr\u00f3meta Herasme, resalt\u00f3 el apoyo incondicional que ha recibido de la alcaldesa Carolina Mej\u00eda, quien ha hecho esfuerzos por fortalecer los servicios que ofrece el organismo de socorro y por mejorar las condiciones en las hacen sus labores estos h\u00e9roes.<\/p>\n\n\n\n<p>\u201cLa se\u00f1ora alcaldesa ha convertido nuestro Cuerpo de Bomberos en una instituci\u00f3n m\u00e1s confiable. D\u00eda a d\u00eda trabajamos junto a la alcald\u00eda, haciendo esfuerzos conjuntos para el beneficio de la ciudad, creando una instituci\u00f3n cada vez m\u00e1s segura\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El alto oficial indic\u00f3 que a finales de mes miembros del Cuerpo de Bomberos realizar\u00e1n un entrenamiento en Puerto Rico con el apoyo de la alcaldesa Mej\u00eda.<\/p>\n\n\n\n<p>6,564 servicios de enero a octubre<\/p>\n\n\n\n<p>Fr\u00f3meta Herasme inform\u00f3 que dieron 6,564 servicios en el a\u00f1o, incluyendo 758 en octubre, que incluyen consultas m\u00e9dicas con 257 asistencias y 183 sobre servicios de agua, as\u00ed como la participaci\u00f3n de su banda musical en diversos actos.<\/p>\n\n\n\n<p>Este organismo de socorro no solo se encarga de salvar vidas, sino tambi\u00e9n de capacitar a la ciudadan\u00eda como una forma de crear mecanismos de defensa en casos de emergencias.<\/p>\n\n\n\n<p>Tambi\u00e9n ofrecen charlas de prevenci\u00f3n, uso y manejo de extintores, primeros auxilios y evacuaci\u00f3n. En ese sentido, Fr\u00f3meta apunt\u00f3 que llevan a cabo inspecciones de la salida de emergencia en espacios privados y servicios p\u00fablicos como bares restaurantes.<\/p>\n\n\n\n<p>El Cuerpo de Bomberos del DN brind\u00f3 29 capacitaciones, 21 certificaciones a establecimientos p\u00fablicos y 12 certificaciones de incendios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El general Fr\u00f3meta Herasme destac\u00f3 el gran apoyo recibido de la alcaldesa Carolina Mej\u00eda Santo Domingo. &#8211; El Cuerpo de Bomberos del Distrito Nacional realiz\u00f3 466 asistencias durante el mes de octubre, completando un total de 5,206 emergencias asistidas desde inicio de enero hasta finales de octubre. A lo largo del mes de octubre los&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[1793,1792,1100],"class_list":["post-3848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-asistencias","tag-cuerpo-de-bomberos","tag-emergencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024 - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024 - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"El general Fr\u00f3meta Herasme destac\u00f3 el gran apoyo recibido de la alcaldesa Carolina Mej\u00eda Santo Domingo. &#8211; El Cuerpo de Bomberos del Distrito Nacional realiz\u00f3 466 asistencias durante el mes de octubre, completando un total de 5,206 emergencias asistidas desde inicio de enero hasta finales de octubre. A lo largo del mes de octubre los...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T18:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1072\" \/>\n\t<meta property=\"og:image:height\" content=\"706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024\",\"datePublished\":\"2024-11-12T18:52:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg\",\"keywords\":[\"Asistencias\",\"Cuerpo de Bomberos\",\"Emergencia\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/\",\"name\":\"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024 - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg\",\"datePublished\":\"2024-11-12T18:52:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg\",\"width\":1072,\"height\":706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/11\\\/12\\\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024 - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024 - Bombazo Informativo","og_description":"El general Fr\u00f3meta Herasme destac\u00f3 el gran apoyo recibido de la alcaldesa Carolina Mej\u00eda Santo Domingo. &#8211; El Cuerpo de Bomberos del Distrito Nacional realiz\u00f3 466 asistencias durante el mes de octubre, completando un total de 5,206 emergencias asistidas desde inicio de enero hasta finales de octubre. A lo largo del mes de octubre los...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-11-12T18:52:58+00:00","og_image":[{"width":1072,"height":706,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024","datePublished":"2024-11-12T18:52:58+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg","keywords":["Asistencias","Cuerpo de Bomberos","Emergencia"],"articleSection":["Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/","name":"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024 - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg","datePublished":"2024-11-12T18:52:58+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg","width":1072,"height":706},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/11\/12\/cuerpo-de-bomberos-del-dn-ha-brindado-5206-asistencias-a-emergencias-entre-enero-y-octubre-de-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Cuerpo de Bomberos del DN ha brindado 5,206 asistencias a emergencias entre enero y octubre de 2024"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.37.46-PM.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3848"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3848\/revisions"}],"predecessor-version":[{"id":3851,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3848\/revisions\/3851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/3849"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}