{"id":3668,"date":"2024-10-23T09:46:24","date_gmt":"2024-10-23T13:46:24","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=3668"},"modified":"2024-10-23T09:46:24","modified_gmt":"2024-10-23T13:46:24","slug":"prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/","title":{"rendered":"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias"},"content":{"rendered":"\n<p>Santo Domingo.-&nbsp;<strong>El mercado internacional de fragancias<\/strong>&nbsp;representa una&nbsp;<strong>oportunidad de crecimiento<\/strong>&nbsp;para la Rep\u00fablica Dominicana en materia de&nbsp;<strong>exportaci\u00f3n<\/strong>, por su aporte a las cadenas de valor de los productos dominicanos. Este es un aspecto que el Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana&nbsp;<strong>(ProDominicana)<\/strong>&nbsp;est\u00e1 impulsando junto con la Agencia de Cooperaci\u00f3n Internacional del Jap\u00f3n&nbsp;<strong>(JICA)<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Ambas entidades se unieron para desarrollar la conferencia&nbsp;<strong>\u201cLa frontera de la creatividad y la exportaci\u00f3n: oportunidades en el mercado global del desarrollo de fragancias\u201d<\/strong>, que cont\u00f3 con la ponencia de la experta japonesa en desarrollo de fragancias,&nbsp;<strong>Haruna Sema<\/strong>, quien dise\u00f1\u00f3 la fragancia para ambientar los Juegos Ol\u00edmpicos de Tokio 2020. La conferencista, de la mano de JICA, expuso sobre aprovechamiento de los&nbsp;<strong>recursos naturales<\/strong>&nbsp;de nuestro pa\u00eds para la&nbsp;<strong>creaci\u00f3n de fragancias<\/strong>.&nbsp;<\/p>\n\n\n\n<p>De su lado,&nbsp;<strong>Carolina P\u00e9rez<\/strong>, directora de la Direcci\u00f3n de Inteligencia de Mercados de ProDominicana, present\u00f3 los servicios que la instituci\u00f3n ofrece a las&nbsp;<strong>empresas exportadoras y mipymes con capacidad para exportar<\/strong>. Estos servicios permiten acceder a herramientas clave para facilitar el acceso a mercados internacionales, recibir alertas comerciales y mantenerse informados sobre&nbsp;<strong>oportunidades de Inversi\u00f3n Extranjera Directa<\/strong>, entre otros.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.presidencia.gob.do\/sites\/default\/files\/inline-images\/IMG_4483.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>En ese sentido,&nbsp;<strong>Biviana Riveiro<\/strong>, directora ejecutiva de ProDominicana, expres\u00f3 que este mercado, de gran relevancia a nivel global, cuenta con un enfoque clave en el&nbsp;<strong>empoderamiento de los empresarios y emprendedores del pa\u00eds<\/strong>, quienes no solo aprender\u00e1n a elaborar productos de fragancias, sino que tambi\u00e9n adquirir\u00e1n&nbsp;<strong>nuevas herramientas para diversificar sus fuentes de ingresos<\/strong>.&nbsp;<em>\u201cEsto es un reflejo de nuestro compromiso en ProDominicana con el desarrollo de todos los sectores, ya que queremos que cada dominicano tenga la capacidad de transformar los recursos naturales en oportunidades econ\u00f3micas sostenibles\u201d<\/em>, asegur\u00f3.&nbsp;<\/p>\n\n\n\n<p>Cabe destacar que, para el per\u00edodo del 2020 hasta septiembre del 2024, la Rep\u00fablica Dominicana ha exportado&nbsp;<strong>m\u00e1s de RD 1,300 millones, por concepto de fragancias y esencias arom\u00e1ticas hacia 45 mercados<\/strong>, en los cuales han participado&nbsp;<strong>m\u00e1s de 300 exportadore<\/strong><strong>s<\/strong>&nbsp;de distintas provincias del pa\u00eds. Estas exportaciones alcanzaron un r\u00e9cord hist\u00f3rico en 2023, al totalizar&nbsp;<strong>USD 6.7 millones<\/strong>, lo que representa un crecimiento de&nbsp;<strong>56 %<\/strong>&nbsp;con respecto al 2022.<\/p>\n\n\n\n<p>La experta&nbsp;<strong>Haruna Sema<\/strong>&nbsp;explic\u00f3 c\u00f3mo puede el pa\u00eds aprovechar diversas&nbsp;<strong>hierbas y plantas<\/strong>&nbsp;que se encuentran en el territorio nacional para extraer&nbsp;<strong>aceites esenciales<\/strong>&nbsp;que les permitan crear fragancias puramente dominicanas&nbsp;<strong>sin necesidad de importar materia prima<\/strong>.&nbsp;&nbsp;<em>\u201cEsta es una excelente oportunidad para fomentar la competitividad del pa\u00eds, el crecimiento y la diversificaci\u00f3n econ\u00f3mica de los emprendedores con inter\u00e9s en incursionar en el mundo de la creaci\u00f3n de fragancias\u201d,&nbsp;<\/em>indic\u00f3.<\/p>\n\n\n\n<p>Mientras que el representante residente de la JICA en el pa\u00eds,&nbsp;<strong>Kota Sakaguchi<\/strong>, explic\u00f3 que la agencia trajo a la Rep\u00fablica Dominicana a la experta Haruna Sema en el marco del programa&nbsp;<strong>\u201cArtistas en Proyecto\u201d.&nbsp;<\/strong>Este consiste en traer al pa\u00eds artistas de diferentes \u00e1reas para agregar valor y cocrear una&nbsp;<strong>nueva herramienta de cooperaci\u00f3n.<\/strong>&nbsp;<\/p>\n\n\n\n<p><em>\u201cDesde la JICA apoyamos al pa\u00eds en diversas \u00e1reas como salud, educaci\u00f3n, medioambiente, turismo, entre otras, y mediante esta nueva herramienta de cooperaci\u00f3n aportamos a la productividad, el emprendimiento y el crecimiento sostenible de la econom\u00eda\u201d,<\/em>&nbsp;expres\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.-&nbsp;El mercado internacional de fragancias&nbsp;representa una&nbsp;oportunidad de crecimiento&nbsp;para la Rep\u00fablica Dominicana en materia de&nbsp;exportaci\u00f3n, por su aporte a las cadenas de valor de los productos dominicanos. Este es un aspecto que el Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana&nbsp;(ProDominicana)&nbsp;est\u00e1 impulsando junto con la Agencia de Cooperaci\u00f3n Internacional del Jap\u00f3n&nbsp;(JICA).&nbsp; Ambas entidades se&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[412,1715,1432,878],"class_list":["post-3668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-exportaciones","tag-fragancias","tag-jica","tag-prodominicana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.-&nbsp;El mercado internacional de fragancias&nbsp;representa una&nbsp;oportunidad de crecimiento&nbsp;para la Rep\u00fablica Dominicana en materia de&nbsp;exportaci\u00f3n, por su aporte a las cadenas de valor de los productos dominicanos. Este es un aspecto que el Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana&nbsp;(ProDominicana)&nbsp;est\u00e1 impulsando junto con la Agencia de Cooperaci\u00f3n Internacional del Jap\u00f3n&nbsp;(JICA).&nbsp; Ambas entidades se...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-23T13:46:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/IMG_4482.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias\",\"datePublished\":\"2024-10-23T13:46:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/\"},\"wordCount\":616,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_4482.jpeg\",\"keywords\":[\"Exportaciones\",\"Fragancias\",\"JICA\",\"ProDominicana\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/\",\"name\":\"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_4482.jpeg\",\"datePublished\":\"2024-10-23T13:46:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_4482.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_4482.jpeg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/23\\\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/","og_locale":"es_ES","og_type":"article","og_title":"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias - Bombazo Informativo","og_description":"Santo Domingo.-&nbsp;El mercado internacional de fragancias&nbsp;representa una&nbsp;oportunidad de crecimiento&nbsp;para la Rep\u00fablica Dominicana en materia de&nbsp;exportaci\u00f3n, por su aporte a las cadenas de valor de los productos dominicanos. Este es un aspecto que el Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana&nbsp;(ProDominicana)&nbsp;est\u00e1 impulsando junto con la Agencia de Cooperaci\u00f3n Internacional del Jap\u00f3n&nbsp;(JICA).&nbsp; Ambas entidades se...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-10-23T13:46:24+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/IMG_4482.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias","datePublished":"2024-10-23T13:46:24+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/"},"wordCount":616,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/IMG_4482.jpeg","keywords":["Exportaciones","Fragancias","JICA","ProDominicana"],"articleSection":["Econom\u00eda"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/","name":"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/IMG_4482.jpeg","datePublished":"2024-10-23T13:46:24+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/IMG_4482.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/IMG_4482.jpeg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/23\/prodominicana-y-la-agencia-de-cooperacion-del-japon-promueven-a-rd-en-el-mercado-internacional-de-fragancias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"ProDominicana y la Agencia de Cooperaci\u00f3n del Jap\u00f3n promueven a RD en el mercado internacional de fragancias"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/IMG_4482.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3668"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3668\/revisions"}],"predecessor-version":[{"id":3670,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3668\/revisions\/3670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/3669"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}