{"id":3505,"date":"2024-10-01T14:43:35","date_gmt":"2024-10-01T18:43:35","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=3505"},"modified":"2024-10-01T14:43:36","modified_gmt":"2024-10-01T18:43:36","slug":"500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/","title":{"rendered":"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo"},"content":{"rendered":"\n<p>Santo Domingo.- Una delegaci\u00f3n de la Comisi\u00f3n Nacional de Elecciones Internas (CNEI) del partido Opci\u00f3n Democr\u00e1tica (OD), entreg\u00f3 este lunes de manera formal a la Junta Central Electoral (JCE) el padr\u00f3n de delegados y delegadas que ser\u00e1n parte de la Asamblea Nacional de este 06 de octubre en la que la organizaci\u00f3n pol\u00edtica elegir\u00e1 a sus nuevos liderazgos para los pr\u00f3ximos 4 a\u00f1os.<\/p>\n\n\n\n<p>Este registro cuenta con al menos 500 personas confirmadas para elegir a las nuevas autoridades partidarias, seg\u00fan inform\u00f3 la comisi\u00f3n en un comunicado.<\/p>\n\n\n\n<p>El partido Opci\u00f3n Democr\u00e1tica est\u00e1 sumergido en un proceso de elecciones internas que busca renovar distintos estamentos de la organizaci\u00f3n pol\u00edtica para los pr\u00f3ximos 4 a\u00f1os. Los mismos incluyen la presidencia, vicepresidencia, secretar\u00eda general, Direcci\u00f3n Pol\u00edtica y Comisi\u00f3n de Garant\u00edas Democr\u00e1ticas.<\/p>\n\n\n\n<p>Para esto llamaron a toda su militancia a registrarse como delegados o delegadas y as\u00ed poder participar de su Asamblea Nacional.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-3507\" srcset=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM-1-1024x768.jpeg 1024w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM-1-300x225.jpeg 300w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM-1-768x576.jpeg 768w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La Asamblea Nacional del partido pol\u00edtico Opci\u00f3n Democr\u00e1tica se celebrar\u00e1 el pr\u00f3ximo domingo 06 de octubre de 2024 a partir de las 8:00 AM., en el Sal\u00f3n de Eventos de Plaza Central, Distrito Nacional.<\/p>\n\n\n\n<p>Hay 33 personas aspirando a formar parte de la Direcci\u00f3n Pol\u00edtica (DP) de esta organizaci\u00f3n que est\u00e1 compuesta por 19 integrantes, y unas 10 personas buscan ser electas como los 5 titulares y 2 suplentes de la Comisi\u00f3n de Garant\u00edas Democr\u00e1ticas (CGD).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- Una delegaci\u00f3n de la Comisi\u00f3n Nacional de Elecciones Internas (CNEI) del partido Opci\u00f3n Democr\u00e1tica (OD), entreg\u00f3 este lunes de manera formal a la Junta Central Electoral (JCE) el padr\u00f3n de delegados y delegadas que ser\u00e1n parte de la Asamblea Nacional de este 06 de octubre en la que la organizaci\u00f3n pol\u00edtica elegir\u00e1 a&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[1638,26,37],"class_list":["post-3505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-delegados","tag-elecciones","tag-opcion-democratica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.- Una delegaci\u00f3n de la Comisi\u00f3n Nacional de Elecciones Internas (CNEI) del partido Opci\u00f3n Democr\u00e1tica (OD), entreg\u00f3 este lunes de manera formal a la Junta Central Electoral (JCE) el padr\u00f3n de delegados y delegadas que ser\u00e1n parte de la Asamblea Nacional de este 06 de octubre en la que la organizaci\u00f3n pol\u00edtica elegir\u00e1 a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T18:43:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T18:43:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo\",\"datePublished\":\"2024-10-01T18:43:35+00:00\",\"dateModified\":\"2024-10-01T18:43:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg\",\"keywords\":[\"Delegados\",\"Elecciones\",\"Opci\u00f3n Democratica\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/\",\"name\":\"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg\",\"datePublished\":\"2024-10-01T18:43:35+00:00\",\"dateModified\":\"2024-10-01T18:43:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/10\\\/01\\\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/","og_locale":"es_ES","og_type":"article","og_title":"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo - Bombazo Informativo","og_description":"Santo Domingo.- Una delegaci\u00f3n de la Comisi\u00f3n Nacional de Elecciones Internas (CNEI) del partido Opci\u00f3n Democr\u00e1tica (OD), entreg\u00f3 este lunes de manera formal a la Junta Central Electoral (JCE) el padr\u00f3n de delegados y delegadas que ser\u00e1n parte de la Asamblea Nacional de este 06 de octubre en la que la organizaci\u00f3n pol\u00edtica elegir\u00e1 a...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-10-01T18:43:35+00:00","article_modified_time":"2024-10-01T18:43:36+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo","datePublished":"2024-10-01T18:43:35+00:00","dateModified":"2024-10-01T18:43:36+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg","keywords":["Delegados","Elecciones","Opci\u00f3n Democratica"],"articleSection":["Pol\u00edtica"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/","name":"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg","datePublished":"2024-10-01T18:43:35+00:00","dateModified":"2024-10-01T18:43:36+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/10\/01\/500-delegados-de-opcion-democratica-eligen-nuevas-autoridades-este-domingo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"500 delegados de Opci\u00f3n Democr\u00e1tica eligen nuevas autoridades este domingo"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-01-at-2.39.20-PM.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3505"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3505\/revisions"}],"predecessor-version":[{"id":3508,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3505\/revisions\/3508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/3506"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}