{"id":3205,"date":"2024-09-02T11:44:43","date_gmt":"2024-09-02T15:44:43","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=3205"},"modified":"2024-09-02T11:44:44","modified_gmt":"2024-09-02T15:44:44","slug":"intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/","title":{"rendered":"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo"},"content":{"rendered":"\n<p>SANTO DOMINGO.- El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant) anunci\u00f3 este lunes la rescisi\u00f3n del contrato con la empresa Transcore Latam SRL, acus\u00e1ndola \u00a0de haber afectado intencionalmente la red semaf\u00f3rica del Gran Santo Domingo, generando caos en el tr\u00e1nsito durante los d\u00edas 28, 29 y 30 de agosto pasado.<\/p>\n\n\n\n<p>Milton Morrison, director del Intrant, inform\u00f3 mediante una rueda de prensa que el Estado ha asumido el control total de la red semaf\u00f3rica para evitar la repetici\u00f3n de incidentes similares. asimismo, solicitaron al Ministerio P\u00fablico iniciar una investigaci\u00f3n para determinar las responsabilidades correspondientes en este caso.<\/p>\n\n\n\n<p>Morrison detall\u00f3 que desde el 27 de agosto los t\u00e9cnicos del Intrant detectaron irregularidades en el sistema de sem\u00e1foros. Al reclamarle a Transcore Latam SRL, la respuesta de la empresa fue, seg\u00fan el funcionario, afectar intencionalmente todo el sistema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant) anunci\u00f3 este lunes la rescisi\u00f3n del contrato con la empresa Transcore Latam SRL, acus\u00e1ndola \u00a0de haber afectado intencionalmente la red semaf\u00f3rica del Gran Santo Domingo, generando caos en el tr\u00e1nsito durante los d\u00edas 28, 29 y 30 de agosto pasado. Milton Morrison, director del&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,24],"tags":[1178,363,1506,201,1507,1508],"class_list":["post-3205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","category-nacionales","tag-cancelaciones","tag-caos","tag-contrato","tag-intrant","tag-semaforos","tag-transcore-latam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"SANTO DOMINGO.- El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant) anunci\u00f3 este lunes la rescisi\u00f3n del contrato con la empresa Transcore Latam SRL, acus\u00e1ndola \u00a0de haber afectado intencionalmente la red semaf\u00f3rica del Gran Santo Domingo, generando caos en el tr\u00e1nsito durante los d\u00edas 28, 29 y 30 de agosto pasado. Milton Morrison, director del...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-02T15:44:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-02T15:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/09\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo\",\"datePublished\":\"2024-09-02T15:44:43+00:00\",\"dateModified\":\"2024-09-02T15:44:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/\"},\"wordCount\":163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg\",\"keywords\":[\"Cancelaciones\",\"Caos\",\"Contrato\",\"Intrant\",\"Sem\u00e1foros\",\"Transcore Latam\"],\"articleSection\":[\"Calientes\",\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/\",\"name\":\"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg\",\"datePublished\":\"2024-09-02T15:44:43+00:00\",\"dateModified\":\"2024-09-02T15:44:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg\",\"width\":696,\"height\":392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/09\\\/02\\\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/","og_locale":"es_ES","og_type":"article","og_title":"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo - Bombazo Informativo","og_description":"SANTO DOMINGO.- El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant) anunci\u00f3 este lunes la rescisi\u00f3n del contrato con la empresa Transcore Latam SRL, acus\u00e1ndola \u00a0de haber afectado intencionalmente la red semaf\u00f3rica del Gran Santo Domingo, generando caos en el tr\u00e1nsito durante los d\u00edas 28, 29 y 30 de agosto pasado. Milton Morrison, director del...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-09-02T15:44:43+00:00","article_modified_time":"2024-09-02T15:44:44+00:00","og_image":[{"width":696,"height":392,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/09\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo","datePublished":"2024-09-02T15:44:43+00:00","dateModified":"2024-09-02T15:44:44+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/"},"wordCount":163,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/09\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg","keywords":["Cancelaciones","Caos","Contrato","Intrant","Sem\u00e1foros","Transcore Latam"],"articleSection":["Calientes","Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/","name":"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/09\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg","datePublished":"2024-09-02T15:44:43+00:00","dateModified":"2024-09-02T15:44:44+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/09\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/09\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg","width":696,"height":392},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/09\/02\/intrant-anuncia-rescision-de-contrato-con-transcore-latam-tras-caos-por-semaforos-de-santo-domingo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Intrant anuncia rescisi\u00f3n de contrato con Transcore Latam tras caos por sem\u00e1foros de Santo Domingo"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/09\/intrant-acusa-a-transcore-latam-de-afectar-red-semaforica-de-gsd-focus-0-0-896-504-696x392-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3205"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3205\/revisions"}],"predecessor-version":[{"id":3207,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3205\/revisions\/3207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/3206"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}