{"id":3163,"date":"2024-08-27T14:36:29","date_gmt":"2024-08-27T18:36:29","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=3163"},"modified":"2024-08-27T14:36:30","modified_gmt":"2024-08-27T18:36:30","slug":"activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/","title":{"rendered":"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana"},"content":{"rendered":"\n<p>Santo Domingo.- La activista y defensora de derechos humanos de grupos vulnerabilizados Rosanna Marz\u00e1n, denunci\u00f3 el hackeo de la p\u00e1gina de Instagram de Diversidad Dominicana, instituci\u00f3n que promueve una sociedad que acepte y respete la diversidad de orientaci\u00f3n sexual y de la cual es directora ejecutiva.<\/p>\n\n\n\n<p>\"Lamentablemente, quienes lo hicieron sab\u00edan muy bien c\u00f3mo hacer el da\u00f1o y lo hicieron sin medir consecuencias, desapareciendo nuestra p\u00e1gina de 8 a\u00f1os de construcci\u00f3n y dinero invertido\", afirm\u00f3 Marz\u00e1n.<\/p>\n\n\n\n<p>La tambi\u00e9n abogada entiende que tal acci\u00f3n tuvo como motivo \"impedir que continuemos nuestro trabajo; querer callarnos, lo cual evidencia mucha perversidad y malicia\".<\/p>\n\n\n\n<p>En ese mismo tenor, la educadora social tambi\u00e9n denunci\u00f3 que no es la primera vez que han pretendido o ejecutado acciones que afecten a la instituci\u00f3n.<\/p>\n\n\n\n<p>\"Han intentado de todo para sacarnos de circulaci\u00f3n: insultos, amenazas de muerte, intentos de asesinato 3 veces y ahora \u00e9sto\", denunci\u00f3.<\/p>\n\n\n\n<p>La activista tambi\u00e9n inform\u00f3 que est\u00e1n \"recolectando toda la informaci\u00f3n y preparando la denuncia ante las autoridades, debido a que esto es un delito y habr\u00e1 consecuencias para los que se han tomado el tiempo de hacernos este da\u00f1o, el cual tendr\u00e1n que reparar\", adelant\u00f3.<\/p>\n\n\n\n<p>No obstante, Marz\u00e1n extern\u00f3 que no podr\u00e1n detener el trabajo que han venido realizando<br>motivado en la lucha por los derechos de las personas LGBTIQ+ a nivel nacional e internacional.<\/p>\n\n\n\n<p>\"La nueva pagina de Instagram es @diversidaddominicana. Acompa\u00f1enos a seguir haciendo comunidad y espacios seguros para nuestra gente\", finaliz\u00f3.<\/p>\n\n\n\n<p>Sobre Rosanna Marz\u00e1n<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"482\" height=\"297\" src=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM.jpeg\" alt=\"\" class=\"wp-image-3165\" srcset=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM.jpeg 482w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-300x185.jpeg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/figure>\n\n\n\n<p>Rosanna Marz\u00e1n, obtuvo el Premio Front Line Defenders 2019, junto a otros cinco galardonadas\/os LGBTI+ de T\u00fanez, Rusia, Indonesia y Malawi.<\/p>\n\n\n\n<p>Asimismo, trabaja con otras activistas por la promoci\u00f3n de derechos a la orientaci\u00f3n sexual, la identidad y expresi\u00f3n de g\u00e9nero y las caracter\u00edsticas sexuales (SOGIESC), para visibilizar y abordar los problemas que enfrentan las personas LGBTIQ, con un foco especial en las mujeres lesbianas, adem\u00e1s de defender derechos de personas migrantes y refugiadas y sobrevivientes de violencia dom\u00e9stica.<\/p>\n\n\n\n<p>Ha participado en la asamblea de la Organizaci\u00f3n de los Estados Americanos como portavoz de la Coalici\u00f3n LGBTTTI de las Am\u00e9ricas en 2016 y estuvo entre las\/os activistas de la primera reuni\u00f3n tem\u00e1tica de LGBTI+ de la Comisi\u00f3n Interamericana de Derechos Humanos de Rep\u00fablica Dominicana en 2015.<\/p>\n\n\n\n<p>Adem\u00e1s, es directora de la \u00fanica Escuela de Liderazgos Pol\u00edticos LGBTI de Rep\u00fablica Dominicana, miembra de diferentes asociaciones internacionales de Derecho y tambi\u00e9n del Colectivo LGBTIQ Dominicano.<\/p>\n\n\n\n<p>En el 2016, fue la Reina del Orgullo LGBTI y portavoz de la Caravana de Orgullo LGBTI de Rep\u00fablica Dominicana de ese mismo a\u00f1o.<\/p>\n\n\n\n<p>Este a\u00f1o form\u00f3 parte del \"Observatorio Regional sobre la Participaci\u00f3n Pol\u00edtica de las personas LGBTIQ+ en Am\u00e9rica Latina y el Caribe\u201d, actividad que busca promover, visibilizar y fortalecer la participaci\u00f3n pol\u00edtica y ciudadana de las personas LGBTIQ+ en Am\u00e9rica Latina y el Caribe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- La activista y defensora de derechos humanos de grupos vulnerabilizados Rosanna Marz\u00e1n, denunci\u00f3 el hackeo de la p\u00e1gina de Instagram de Diversidad Dominicana, instituci\u00f3n que promueve una sociedad que acepte y respete la diversidad de orientaci\u00f3n sexual y de la cual es directora ejecutiva. \"Lamentablemente, quienes lo hicieron sab\u00edan muy bien c\u00f3mo hacer&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1480,852,916,1481],"class_list":["post-3163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-activista","tag-diversidad-dominicana","tag-hackeo","tag-instagram"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.- La activista y defensora de derechos humanos de grupos vulnerabilizados Rosanna Marz\u00e1n, denunci\u00f3 el hackeo de la p\u00e1gina de Instagram de Diversidad Dominicana, instituci\u00f3n que promueve una sociedad que acepte y respete la diversidad de orientaci\u00f3n sexual y de la cual es directora ejecutiva. &quot;Lamentablemente, quienes lo hicieron sab\u00edan muy bien c\u00f3mo hacer...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T18:36:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-27T18:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana\",\"datePublished\":\"2024-08-27T18:36:29+00:00\",\"dateModified\":\"2024-08-27T18:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/\"},\"wordCount\":524,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg\",\"keywords\":[\"Activista\",\"Diversidad Dominicana\",\"Hackeo\",\"Instagram\"],\"articleSection\":[\"Calientes\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/\",\"name\":\"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg\",\"datePublished\":\"2024-08-27T18:36:29+00:00\",\"dateModified\":\"2024-08-27T18:36:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg\",\"width\":719,\"height\":536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/27\\\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/","og_locale":"es_ES","og_type":"article","og_title":"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana - Bombazo Informativo","og_description":"Santo Domingo.- La activista y defensora de derechos humanos de grupos vulnerabilizados Rosanna Marz\u00e1n, denunci\u00f3 el hackeo de la p\u00e1gina de Instagram de Diversidad Dominicana, instituci\u00f3n que promueve una sociedad que acepte y respete la diversidad de orientaci\u00f3n sexual y de la cual es directora ejecutiva. \"Lamentablemente, quienes lo hicieron sab\u00edan muy bien c\u00f3mo hacer...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-08-27T18:36:29+00:00","article_modified_time":"2024-08-27T18:36:30+00:00","og_image":[{"width":719,"height":536,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana","datePublished":"2024-08-27T18:36:29+00:00","dateModified":"2024-08-27T18:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/"},"wordCount":524,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg","keywords":["Activista","Diversidad Dominicana","Hackeo","Instagram"],"articleSection":["Calientes"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/","name":"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg","datePublished":"2024-08-27T18:36:29+00:00","dateModified":"2024-08-27T18:36:30+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg","width":719,"height":536},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/27\/activista-rosanna-marzan-denuncia-hackeo-instagram-de-diversidad-dominicana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Activista Rosanna Marz\u00e1n denuncia hackeo Instagram de Diversidad Dominicana"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-27-at-2.26.56-PM-1.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3163"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3163\/revisions"}],"predecessor-version":[{"id":3166,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3163\/revisions\/3166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/3164"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}