{"id":3032,"date":"2024-08-07T13:16:06","date_gmt":"2024-08-07T17:16:06","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=3032"},"modified":"2024-08-07T13:16:06","modified_gmt":"2024-08-07T17:16:06","slug":"temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/","title":{"rendered":"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro"},"content":{"rendered":"\n<p><strong>T\u00e1chira, Venezuela.<\/strong>&nbsp;-\u00abNo se ve la luz al final del t\u00fanel. Me voy\u00bb, dice con decepci\u00f3n Jos\u00e9 V\u00e1squez en T\u00e1chira, un estado de&nbsp;<strong>Venezuela<\/strong>&nbsp;fronterizo con Colombia, tras la reelecci\u00f3n del presidente&nbsp;<strong>Nicol\u00e1s Maduro<\/strong>, denunciada como un&nbsp;<strong>fraude<\/strong>&nbsp;por la oposici\u00f3n.<\/p>\n\n\n\n<p>Gobiernos de la regi\u00f3n temen que&nbsp;<strong>venezolanos<\/strong>&nbsp;como \u00e9l puedan integrar una nueva oleada&nbsp;<strong>migratoria<\/strong>, luego de que 7.5 millones de personas dejaran este pa\u00eds caribe\u00f1o durante la \u00faltima d\u00e9cada para huir de una voraz crisis, seg\u00fan estimaciones de la Agencia de la ONU para los Refugiados (ACNUR).<\/p>\n\n\n\n<p>\u00abEstoy triste, cansado, aburrido. Fue un robo descarado\u00bb, lamenta V\u00e1squez, de 31 a\u00f1os. Aunque estudi\u00f3&nbsp;<strong>Educaci\u00f3n<\/strong>, ahora es vendedor de un local comercial en San Crist\u00f3bal, capital de T\u00e1chira, por los bajos salarios de los&nbsp;<strong>profesores<\/strong>, que, sostiene, \u00abno sirven para nada\u00bb.<\/p>\n\n\n\n<p>\u00abTodo el mundo sabe lo que va a pasar: la gente de mi edad y la que es m\u00e1s jovencita se va a ir. Va a haber una fuga&nbsp;<strong>migratoria<\/strong>&nbsp;gigantesca. La&nbsp;<strong>di\u00e1spora<\/strong>&nbsp;va a ser mayor\u00bb, comenta sentado en la c\u00e9ntrica plaza Bol\u00edvar de esta ciudad, un \u00e1rea de intensa actividad comercial que estaba pr\u00e1cticamente desierta por el temor a disturbios tras las elecciones, en una regi\u00f3n en la que hubo violentas protestas en 2014, 2017 y 2019.<\/p>\n\n\n\n<p>\u00abHay&nbsp;<strong>zozobra<\/strong>,&nbsp;<strong>incertidumbre<\/strong>\u00ab, expresa mientras apunta con la mano hacia las rejas bajadas de los locales aleda\u00f1os.<\/p>\n\n\n\n<p>V\u00e1squez piensa en irse a&nbsp;<strong>Espa\u00f1a<\/strong>, donde familiares directos viven desde hace diez a\u00f1os. \u00abYo ten\u00eda esperanzas en este proceso electoral (\u2026), ahora hay que pensar&nbsp;<strong>alternativas<\/strong>\u00ab, indica.<\/p>\n\n\n\n<p>Antes de los comicios, la encuestadora ORC Consultores proyectaba que 18% de los&nbsp;<strong>venezolanos<\/strong>&nbsp;estar\u00eda dispuesto a&nbsp;<strong>migrar<\/strong>&nbsp;en un plazo de seis meses si Maduro conservaba el poder. Sobre una poblaci\u00f3n de unos 30 millones -el \u00faltimo censo fue en 2011-, ser\u00edan 5.4 millones de personas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">El flujo va a aumentar<\/h4>\n\n\n\n<p>A poco m\u00e1s de una hora por carretera de San Crist\u00f3bal est\u00e1 San Antonio, habitual punto de partida de los&nbsp;<strong>migrantes<\/strong>&nbsp;que salen a pie hacia Estados Unidos con la idea de cruzar la selva del&nbsp;<strong>Dari\u00e9n<\/strong>, peligroso corredor entre Colombia y Panam\u00e1.<\/p>\n\n\n\n<p>\u00abYo creo, ojal\u00e1 me equivoque, que el flujo de&nbsp;<strong>venezolanos<\/strong>&nbsp;(por el&nbsp;<strong>Dari\u00e9n<\/strong>) va a aumentar por razones evidentes. Tenemos que adoptar las decisiones que correspondan tambi\u00e9n para salvaguardar su vida, su integridad y darle paso expedito\u00bb, dijo en rueda de prensa el presidente paname\u00f1o, Jos\u00e9 Ra\u00fal Mulino.<\/p>\n\n\n\n<p>Unos 200,000&nbsp;<strong>migrantes<\/strong>&nbsp;han hecho esta traves\u00eda en 2024, seg\u00fan cifras oficiales. Cerca de dos tercios eran&nbsp;<strong>venezolanos<\/strong>.<\/p>\n\n\n\n<p>Es un tema central en la campa\u00f1a presidencial de Estados Unidos, sobre todo para&nbsp;<strong>Donald Trump<\/strong>, que busca volver a la Casa Blanca con un discurso&nbsp;<strong>antiinmigrantes<\/strong>&nbsp;a\u00fan m\u00e1s fuerte que en su primer mandato (2017-2021).<\/p>\n\n\n\n<p>Ya el Servicio Nacional de Fronteras de Panam\u00e1 anunci\u00f3 que las medidas de&nbsp;<strong>seguridad<\/strong>&nbsp;ser\u00e1n reforzadas en la zona.<\/p>\n\n\n\n<p>El independiente Observatorio de Investigaciones Sociales en la Frontera (ODISEF), en T\u00e1chira, advierte en un informe sobre la \u00ab<strong>vulnerabilidad<\/strong>\u00bb de los&nbsp;<strong>migrantes<\/strong>&nbsp;que cruzan a pie frente a redes de&nbsp;<strong>tr\u00e1fico humano<\/strong>&nbsp;y organizaciones criminales.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Tenemos que\u00a0<strong>prepararnos<\/strong><\/h4>\n\n\n\n<p>Seg\u00fan las estimaciones de Naciones Unidas, que el gobierno de Maduro rechaza, los cinco pa\u00edses de&nbsp;<strong>Latinoam\u00e9rica<\/strong>&nbsp;con mayor n\u00famero de&nbsp;<strong>migrantes<\/strong>&nbsp;de&nbsp;<strong>Venezuela<\/strong>&nbsp;son Colombia (2.8 millones), Per\u00fa (1.5 millones), Brasil (568,000), Chile (532,000) y Ecuador (444,000).<\/p>\n\n\n\n<p>\u00abLa ola&nbsp;<strong>migratoria<\/strong>&nbsp;no se ha detenido en ning\u00fan minuto\u00bb, pero \u00abhay una preocupaci\u00f3n de que esto se pudiera intensificar y para eso tenemos que&nbsp;<strong>prepararnos<\/strong>\u00ab, dijo a la prensa este mi\u00e9rcoles la vicepresidenta de Chile y ministra de Interior, Carolina Toh\u00e1.<\/p>\n\n\n\n<p>Per\u00fa, en tanto, anunci\u00f3 que reforz\u00f3 sus&nbsp;<strong>controles migratorios<\/strong>.<\/p>\n\n\n\n<p>\u00abNo podemos acoger (a&nbsp;<strong>migrantes<\/strong>) en las magnitudes del anterior \u00e9xodo\u00bb, advirti\u00f3 el canciller peruano, Javier Gonz\u00e1lez-Olaechea, en declaraciones a la radio RPP.<\/p>\n\n\n\n<p>Estados Unidos y varios pa\u00edses latinoamericanos han pedido a&nbsp;<strong>Venezuela<\/strong>&nbsp;divulgar las actas de votaci\u00f3n para que puedan ser verificadas frente a las denuncias de&nbsp;<strong>fraude<\/strong>&nbsp;de la oposici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00e1chira, Venezuela.&nbsp;-\u00abNo se ve la luz al final del t\u00fanel. Me voy\u00bb, dice con decepci\u00f3n Jos\u00e9 V\u00e1squez en T\u00e1chira, un estado de&nbsp;Venezuela&nbsp;fronterizo con Colombia, tras la reelecci\u00f3n del presidente&nbsp;Nicol\u00e1s Maduro, denunciada como un&nbsp;fraude&nbsp;por la oposici\u00f3n. Gobiernos de la regi\u00f3n temen que&nbsp;venezolanos&nbsp;como \u00e9l puedan integrar una nueva oleada&nbsp;migratoria, luego de que 7.5 millones de personas dejaran&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[1431,859,1430,129],"class_list":["post-3032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-maduro","tag-migrantes","tag-reeleccion","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"T\u00e1chira, Venezuela.&nbsp;-\u00abNo se ve la luz al final del t\u00fanel. Me voy\u00bb, dice con decepci\u00f3n Jos\u00e9 V\u00e1squez en T\u00e1chira, un estado de&nbsp;Venezuela&nbsp;fronterizo con Colombia, tras la reelecci\u00f3n del presidente&nbsp;Nicol\u00e1s Maduro, denunciada como un&nbsp;fraude&nbsp;por la oposici\u00f3n. Gobiernos de la regi\u00f3n temen que&nbsp;venezolanos&nbsp;como \u00e9l puedan integrar una nueva oleada&nbsp;migratoria, luego de que 7.5 millones de personas dejaran...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-07T17:16:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro\",\"datePublished\":\"2024-08-07T17:16:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/\"},\"wordCount\":758,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg\",\"keywords\":[\"Maduro\",\"Migrantes\",\"Reelecci\u00f3n\",\"Venezuela\"],\"articleSection\":[\"Internacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/\",\"name\":\"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg\",\"datePublished\":\"2024-08-07T17:16:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg\",\"width\":696,\"height\":392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/08\\\/07\\\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/","og_locale":"es_ES","og_type":"article","og_title":"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro - Bombazo Informativo","og_description":"T\u00e1chira, Venezuela.&nbsp;-\u00abNo se ve la luz al final del t\u00fanel. Me voy\u00bb, dice con decepci\u00f3n Jos\u00e9 V\u00e1squez en T\u00e1chira, un estado de&nbsp;Venezuela&nbsp;fronterizo con Colombia, tras la reelecci\u00f3n del presidente&nbsp;Nicol\u00e1s Maduro, denunciada como un&nbsp;fraude&nbsp;por la oposici\u00f3n. Gobiernos de la regi\u00f3n temen que&nbsp;venezolanos&nbsp;como \u00e9l puedan integrar una nueva oleada&nbsp;migratoria, luego de que 7.5 millones de personas dejaran...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-08-07T17:16:06+00:00","og_image":[{"width":696,"height":392,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro","datePublished":"2024-08-07T17:16:06+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/"},"wordCount":758,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg","keywords":["Maduro","Migrantes","Reelecci\u00f3n","Venezuela"],"articleSection":["Internacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/","name":"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg","datePublished":"2024-08-07T17:16:06+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg","width":696,"height":392},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/08\/07\/temen-nueva-oleada-migratoria-tras-reeleccion-de-maduro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Temen nueva oleada migratoria tras reelecci\u00f3n de Maduro"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/08\/crisis-en-venezuela-migracion-y-elecciones-focus-0-0-896-504-696x392-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3032"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3032\/revisions"}],"predecessor-version":[{"id":3034,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3032\/revisions\/3034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/3033"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}