{"id":276,"date":"2024-01-10T14:01:00","date_gmt":"2024-01-10T18:01:00","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=276"},"modified":"2024-01-10T14:01:00","modified_gmt":"2024-01-10T18:01:00","slug":"hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/","title":{"rendered":"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral"},"content":{"rendered":"\n<p>Santo Domingo. &#8211; El Hospital Salvador B. Gautier (HSBG) anunci\u00f3 este mi\u00e9rcoles su XX jornada de cirug\u00edas de columna vertebral, en conjunto con la Fundaci\u00f3n World Spine Outreach, en beneficio de ni\u00f1os, adolescentes y adultos con deformidades y patolog\u00edas degenerativas, especialmente de familias de escasos recursos.<\/p>\n\n\n\n<p>Los pacientes para intervenir saldr\u00e1n seleccionados de entre un grupo de 30 que ser\u00e1n evaluados el primer d\u00eda de la jornada, que se desarrollar\u00e1 desde el domingo 4 de febrero y hasta el s\u00e1bado 10, en los diferentes quir\u00f3fanos del Gautier.<\/p>\n\n\n\n<p>El coordinador de la jornada y director del Departamento de Ortopedia del Gautier, doctor Fredis de Jes\u00fas Reyes Ag\u00fcero, manifest\u00f3 su satisfacci\u00f3n en el entendido de que decenas de familias depositan en este tipo de cirug\u00eda, la esperanza de vida de sus parientes, que han padecido diferentes tipos de deformaciones en su columna vertebral.<\/p>\n\n\n\n<p>\u201cAgradecemos de manera especial a la Fundaci\u00f3n World Spine Outreach y a todos los m\u00e9dicos locales e internacionales que se unir\u00e1n en esta importante jornada para familias de escasos recursos econ\u00f3micos,\u201d sostuvo Reyes Ag\u00fcero.<\/p>\n\n\n\n<p>Mientras que el director del centro, doctor Armando Holgu\u00edn, expres\u00f3 su regocijo por realizarse nueva vez la jornada m\u00e9dica, por lo costosas que son, aunque los seguros cubren los gastos m\u00e9dicos locales, y para los que no tienen recursos, el hospital y el Servicio Nacional de Salud (SNS) apoyan y les facilitan ayuda.<\/p>\n\n\n\n<p>Para esta actividad, la Fundaci\u00f3n World Spice Outreach aporta los implantes que son sumamente costosos donados por esa v\u00eda por empresas internacionales, que colaboran tambi\u00e9n con materiales y otros insumos para las cirug\u00edas, al igual que el Hospital Gautier.<\/p>\n\n\n\n<p>Estas acciones, adem\u00e1s enriquecen el intercambio docente entre los extranjeros y los dominicanos, tanto los m\u00e9dicos ayudantes como los residentes del Departamento de Ortopedia del HSBG.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. &#8211; El Hospital Salvador B. Gautier (HSBG) anunci\u00f3 este mi\u00e9rcoles su XX jornada de cirug\u00edas de columna vertebral, en conjunto con la Fundaci\u00f3n World Spine Outreach, en beneficio de ni\u00f1os, adolescentes y adultos con deformidades y patolog\u00edas degenerativas, especialmente de familias de escasos recursos. Los pacientes para intervenir saldr\u00e1n seleccionados de entre un&#8230;<\/p>\n","protected":false},"author":4,"featured_media":277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22],"tags":[47,46],"class_list":["post-276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-cirugia","tag-hospital-salvador-b-gautier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo. &#8211; El Hospital Salvador B. Gautier (HSBG) anunci\u00f3 este mi\u00e9rcoles su XX jornada de cirug\u00edas de columna vertebral, en conjunto con la Fundaci\u00f3n World Spine Outreach, en beneficio de ni\u00f1os, adolescentes y adultos con deformidades y patolog\u00edas degenerativas, especialmente de familias de escasos recursos. Los pacientes para intervenir saldr\u00e1n seleccionados de entre un...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-10T18:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/01\/Hospital.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral\",\"datePublished\":\"2024-01-10T18:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hospital.jpeg\",\"keywords\":[\"Cirug\u00eda\",\"Hospital Salvador B Gautier\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/\",\"name\":\"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hospital.jpeg\",\"datePublished\":\"2024-01-10T18:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hospital.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Hospital.jpeg\",\"width\":640,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/01\\\/10\\\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/","og_locale":"es_ES","og_type":"article","og_title":"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral - Bombazo Informativo","og_description":"Santo Domingo. &#8211; El Hospital Salvador B. Gautier (HSBG) anunci\u00f3 este mi\u00e9rcoles su XX jornada de cirug\u00edas de columna vertebral, en conjunto con la Fundaci\u00f3n World Spine Outreach, en beneficio de ni\u00f1os, adolescentes y adultos con deformidades y patolog\u00edas degenerativas, especialmente de familias de escasos recursos. Los pacientes para intervenir saldr\u00e1n seleccionados de entre un...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-01-10T18:01:00+00:00","og_image":[{"width":640,"height":400,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/01\/Hospital.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral","datePublished":"2024-01-10T18:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/01\/Hospital.jpeg","keywords":["Cirug\u00eda","Hospital Salvador B Gautier"],"articleSection":["Salud"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/","name":"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/01\/Hospital.jpeg","datePublished":"2024-01-10T18:01:00+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/01\/Hospital.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/01\/Hospital.jpeg","width":640,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/01\/10\/hospital-salvador-b-gautier-anuncia-xx-jornada-de-cirugias-de-columna-vertebral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Hospital Salvador B. Gautier anuncia XX jornada de cirug\u00edas de columna vertebral"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/01\/Hospital.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/276\/revisions"}],"predecessor-version":[{"id":278,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/276\/revisions\/278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/277"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}