{"id":2621,"date":"2024-07-12T09:23:37","date_gmt":"2024-07-12T13:23:37","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=2621"},"modified":"2024-07-12T09:23:38","modified_gmt":"2024-07-12T13:23:38","slug":"presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/","title":{"rendered":"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa"},"content":{"rendered":"\n<p>Santo Domingo.- El&nbsp;<strong>presidente Luis Abinader<\/strong>&nbsp;dej\u00f3 inaugurada la&nbsp;<strong>Plaza del Caf\u00e9, en Jarabacoa<\/strong>, un espacio tur\u00edstico&nbsp;<strong>para dar a conocer el caf\u00e9 local<\/strong>&nbsp;e iniciar los pasos para que los j\u00f3venes incursionen en su producci\u00f3n<strong>, emprendan y generen empleos.&nbsp;<\/strong><\/p>\n\n\n\n<p>De su lado, el director de Proyectos del&nbsp;<strong>Ministerio Administrativo de la Presidencia, Johnny Gonz\u00e1lez,<\/strong>&nbsp;manifest\u00f3 que el gobierno, a trav\u00e9s de la instituci\u00f3n a la que pertenece, ha invertido m\u00e1s de&nbsp;<strong>536 millones de pesos,<\/strong>&nbsp;y que, en el municipio de Jarabacoa y sus distritos, se han invertido m\u00e1s de&nbsp;<strong>125 millones de pesos.<\/strong><\/p>\n\n\n\n<p>Precis\u00f3 que se han construido&nbsp;<strong>parques recreativos, canchas&nbsp;<\/strong>deportivas<strong>, iglesias<\/strong>, se han otorgado&nbsp;<strong>becas&nbsp;<\/strong>estudiantiles, compras de equipos pesados,&nbsp;<strong>ambulancias y camiones de bomberos.<\/strong><\/p>\n\n\n\n<p>Por su parte,&nbsp;<strong>el presidente de ASCAJA, Reyes Hern\u00e1ndez<\/strong>, agradeci\u00f3 al mandatario por el&nbsp;<strong>apoyo a los caficultores,<\/strong>&nbsp;no solo de Jarabacoa, sino del pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.presidencia.gob.do\/sites\/default\/files\/inline-images\/151976d0-b5b2-48ef-bf2b-a68d61bdc50a.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>Presidente Abinader deja inaugurado Festival de Las Flores en Jarabacoa<\/strong><\/p>\n\n\n\n<p>El presidente Abinader, junto con la&nbsp;<strong>primera dama, Raquel Arbaje,&nbsp;<\/strong>dej\u00f3 inaugurado este jueves&nbsp;<strong>el XIII Festival de Las Flores<\/strong>, que se celebra en el&nbsp;<strong>Parque Ecol\u00f3gico La Confluencia<\/strong>, siendo el primer mandatario que asiste a dicho acto.<\/p>\n\n\n\n<p>El festival, que lleva el lema&nbsp;<strong>\"Bajo la primavera que contagia\",&nbsp;<\/strong>se estar\u00e1 llevando a cabo&nbsp;<strong>del 11 al 14 de julio<\/strong>, de 9:30 de la ma\u00f1ana a 10:00 de la noche, donde los visitantes podr\u00e1n disfrutar de presentaciones art\u00edsticas, variedad de opciones de establecimientos de&nbsp;<strong>flores, plantas tropicales, comida y productos artesanales.<\/strong><\/p>\n\n\n\n<p>El mandatario concluy\u00f3 su agenda de este jueves en Jarabacoa, con una reuni\u00f3n a la que asistieron diferentes sectores de la comunidad, y con quienes trat\u00f3 la problem\u00e1tica y su soluci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El&nbsp;presidente Luis Abinader&nbsp;dej\u00f3 inaugurada la&nbsp;Plaza del Caf\u00e9, en Jarabacoa, un espacio tur\u00edstico&nbsp;para dar a conocer el caf\u00e9 local&nbsp;e iniciar los pasos para que los j\u00f3venes incursionen en su producci\u00f3n, emprendan y generen empleos.&nbsp; De su lado, el director de Proyectos del&nbsp;Ministerio Administrativo de la Presidencia, Johnny Gonz\u00e1lez,&nbsp;manifest\u00f3 que el gobierno, a trav\u00e9s de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41],"tags":[1214,531,1215,107,1213,130],"class_list":["post-2621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales","tag-festival-de-las-flores","tag-inauguracion","tag-jarabacoa","tag-luis-abinader","tag-plaza-del-cafe","tag-presidente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.- El&nbsp;presidente Luis Abinader&nbsp;dej\u00f3 inaugurada la&nbsp;Plaza del Caf\u00e9, en Jarabacoa, un espacio tur\u00edstico&nbsp;para dar a conocer el caf\u00e9 local&nbsp;e iniciar los pasos para que los j\u00f3venes incursionen en su producci\u00f3n, emprendan y generen empleos.&nbsp; De su lado, el director de Proyectos del&nbsp;Ministerio Administrativo de la Presidencia, Johnny Gonz\u00e1lez,&nbsp;manifest\u00f3 que el gobierno, a trav\u00e9s de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T13:23:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T13:23:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/9067fd64-f37f-49df-b075-867958adec91.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa\",\"datePublished\":\"2024-07-12T13:23:37+00:00\",\"dateModified\":\"2024-07-12T13:23:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/9067fd64-f37f-49df-b075-867958adec91.jpeg\",\"keywords\":[\"Festival de las Flores\",\"Inauguraci\u00f3n\",\"Jarabacoa\",\"Luis Abinader\",\"Plaza del Caf\u00e9\",\"Presidente\"],\"articleSection\":[\"Regionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/\",\"name\":\"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/9067fd64-f37f-49df-b075-867958adec91.jpeg\",\"datePublished\":\"2024-07-12T13:23:37+00:00\",\"dateModified\":\"2024-07-12T13:23:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/9067fd64-f37f-49df-b075-867958adec91.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/9067fd64-f37f-49df-b075-867958adec91.jpeg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/12\\\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa - Bombazo Informativo","og_description":"Santo Domingo.- El&nbsp;presidente Luis Abinader&nbsp;dej\u00f3 inaugurada la&nbsp;Plaza del Caf\u00e9, en Jarabacoa, un espacio tur\u00edstico&nbsp;para dar a conocer el caf\u00e9 local&nbsp;e iniciar los pasos para que los j\u00f3venes incursionen en su producci\u00f3n, emprendan y generen empleos.&nbsp; De su lado, el director de Proyectos del&nbsp;Ministerio Administrativo de la Presidencia, Johnny Gonz\u00e1lez,&nbsp;manifest\u00f3 que el gobierno, a trav\u00e9s de...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-07-12T13:23:37+00:00","article_modified_time":"2024-07-12T13:23:38+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/9067fd64-f37f-49df-b075-867958adec91.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa","datePublished":"2024-07-12T13:23:37+00:00","dateModified":"2024-07-12T13:23:38+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/9067fd64-f37f-49df-b075-867958adec91.jpeg","keywords":["Festival de las Flores","Inauguraci\u00f3n","Jarabacoa","Luis Abinader","Plaza del Caf\u00e9","Presidente"],"articleSection":["Regionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/","name":"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/9067fd64-f37f-49df-b075-867958adec91.jpeg","datePublished":"2024-07-12T13:23:37+00:00","dateModified":"2024-07-12T13:23:38+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/9067fd64-f37f-49df-b075-867958adec91.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/9067fd64-f37f-49df-b075-867958adec91.jpeg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/12\/presidente-abinader-inaugura-plaza-del-cafe-y-el-festival-de-las-flores-en-jarabacoa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Presidente Abinader inaugura Plaza del Caf\u00e9 y el Festival de Las Flores en Jarabacoa"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/9067fd64-f37f-49df-b075-867958adec91.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2621"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2621\/revisions"}],"predecessor-version":[{"id":2623,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2621\/revisions\/2623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/2622"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}