{"id":2578,"date":"2024-07-05T12:09:55","date_gmt":"2024-07-05T16:09:55","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=2578"},"modified":"2024-07-05T12:09:56","modified_gmt":"2024-07-05T16:09:56","slug":"alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/","title":{"rendered":"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Brigadas han estado en las calles haciendo trabajos preventivos permanentes<\/h2>\n\n\n\n<p>Santo Domingo, DN &#8211; Por disposici\u00f3n de la alcaldesa Carolina Mej\u00eda, la Alcald\u00eda del Distrito Nacional dispuso desde el lunes m\u00e1s de 1,800 personas, entre bomberos y personal operativo para labores de respuesta ante los efectos de las recientes lluvias.<\/p>\n\n\n\n<p>Se trata de un reforzamiento de las labores para mitigar los efectos dejados inicialmente por el hurac\u00e1n Beryl, ahora por una onda tropical que provoc\u00f3 que el Distrito Nacional fuera colocado bajo alerta roja por el Centro de Operaciones de Emergencias (COE).<\/p>\n\n\n\n<p>Brigadas del ayuntamiento que estuvieron trabajando previo y durante las lluvias en las limpiezas de imbornales y filtrantes, ahora son reforzadas para que las v\u00edas y espacios vuelvan a la normalidad a la brevedad posible.<\/p>\n\n\n\n<p>Ha sido notable la presencia de los camiones succionadores y otros equipos en varios puntos cr\u00edticos de la ciudad en los que se han producido inundaciones.<\/p>\n\n\n\n<p>El cabildo hizo un llamado a la ciudadan\u00eda para que est\u00e9 atenta a las posibles lluvias, inform\u00e1ndose a trav\u00e9s de los boletines e informaciones que ofrecen los organismos oficiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brigadas han estado en las calles haciendo trabajos preventivos permanentes Santo Domingo, DN &#8211; Por disposici\u00f3n de la alcaldesa Carolina Mej\u00eda, la Alcald\u00eda del Distrito Nacional dispuso desde el lunes m\u00e1s de 1,800 personas, entre bomberos y personal operativo para labores de respuesta ante los efectos de las recientes lluvias. Se trata de un reforzamiento&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[1079,820,1188],"class_list":["post-2578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-adn","tag-alcaldia-2","tag-fenomenos-atmosfericos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Brigadas han estado en las calles haciendo trabajos preventivos permanentes Santo Domingo, DN &#8211; Por disposici\u00f3n de la alcaldesa Carolina Mej\u00eda, la Alcald\u00eda del Distrito Nacional dispuso desde el lunes m\u00e1s de 1,800 personas, entre bomberos y personal operativo para labores de respuesta ante los efectos de las recientes lluvias. Se trata de un reforzamiento...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-05T16:09:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-05T16:09:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1251\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos\",\"datePublished\":\"2024-07-05T16:09:55+00:00\",\"dateModified\":\"2024-07-05T16:09:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/\"},\"wordCount\":216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg\",\"keywords\":[\"ADN\",\"Alcaldia\",\"Fen\u00f3menos Atmosf\u00e9ricos\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/\",\"name\":\"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg\",\"datePublished\":\"2024-07-05T16:09:55+00:00\",\"dateModified\":\"2024-07-05T16:09:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg\",\"width\":1251,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/07\\\/05\\\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/","og_locale":"es_ES","og_type":"article","og_title":"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos - Bombazo Informativo","og_description":"Brigadas han estado en las calles haciendo trabajos preventivos permanentes Santo Domingo, DN &#8211; Por disposici\u00f3n de la alcaldesa Carolina Mej\u00eda, la Alcald\u00eda del Distrito Nacional dispuso desde el lunes m\u00e1s de 1,800 personas, entre bomberos y personal operativo para labores de respuesta ante los efectos de las recientes lluvias. Se trata de un reforzamiento...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-07-05T16:09:55+00:00","article_modified_time":"2024-07-05T16:09:56+00:00","og_image":[{"width":1251,"height":1600,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos","datePublished":"2024-07-05T16:09:55+00:00","dateModified":"2024-07-05T16:09:56+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/"},"wordCount":216,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg","keywords":["ADN","Alcaldia","Fen\u00f3menos Atmosf\u00e9ricos"],"articleSection":["Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/","name":"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg","datePublished":"2024-07-05T16:09:55+00:00","dateModified":"2024-07-05T16:09:56+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg","width":1251,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/07\/05\/alcaldia-del-dn-dice-ha-dispuesto-mas-de-1800-personas-para-labores-preventivas-y-de-respuesta-ante-efectos-de-los-fenomenos-atmosfericos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Alcald\u00eda del DN dice ha dispuesto m\u00e1s de 1,800 personas para labores preventivas y de respuesta ante efectos de los fen\u00f3menos atmosf\u00e9ricos"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-12.05.23-PM.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2578"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2578\/revisions"}],"predecessor-version":[{"id":2580,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2578\/revisions\/2580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/2579"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}