{"id":2266,"date":"2024-06-14T09:26:53","date_gmt":"2024-06-14T13:26:53","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=2266"},"modified":"2024-06-14T09:26:54","modified_gmt":"2024-06-14T13:26:54","slug":"indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/","title":{"rendered":"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica"},"content":{"rendered":"\n<p>Santo Domingo.- El Instituto Nacional de Recursos Hidr\u00e1ulicos (INDRHI) inform\u00f3 que junto a las entidades competentes mantienen el monitoreo del agua captada en los principales embalses del pa\u00eds, enfatizando que actualmente las presas se encuentran en un buen nivel, y que solo en el embalse de Tavera est\u00e1n implementando medidas para llevarlo al nivel de regla de la temporada cicl\u00f3nica.<\/p>\n\n\n\n<p>En ese tenor, el organismo anunci\u00f3 que en la presa de Tavera, localizada en la provincia Santiago, mantienen en operaci\u00f3n una unidad de generaci\u00f3n en l\u00ednea 24 horas y la segunda unidad por doce horas para llevarla al nivel de regla, que es de 320 metros sobre el nivel del mar. Ambas unidades conducen hasta el cauce del r\u00edo Yaque del Norte unos 60 metros c\u00fabicos por segundo, como medida de precauci\u00f3n ante posibles fen\u00f3menos hidro-meteorol\u00f3gicos.<\/p>\n\n\n\n<p>Olmedo Caba Romano, director ejecutivo de la entidad h\u00eddrica, ha referido en diversos medios de comunicaci\u00f3n que la operatividad de las presas es un ejercicio b\u00e1sico en la gesti\u00f3n del agua en el pa\u00eds; explicando que el abastecimiento del recurso se planifica para garantizar que llegue a acueductos, sistemas de riego e hidroel\u00e9ctricas, entre otros usos, y que a esos fines se re\u00fane cada semana el Observatorio Nacional del Agua.<\/p>\n\n\n\n<p>En ese sentido, indic\u00f3 que la medida de conducir hacia el cauce del r\u00edo unos 60 m3 por segundo se tom\u00f3 en la m\u00e1s reciente reuni\u00f3n conjunta del Comit\u00e9 de Operaci\u00f3n de Presas y Embalses (COPRE) y del Observatorio del Agua, que encabeza el INDRHI y donde convergen las entidades del sector agua.<\/p>\n\n\n\n<p>En la reuni\u00f3n, adem\u00e1s del INDRHI, participaron representantes de la Oficina Nacional de Meteorolog\u00eda (ONAMET), de los Ministerios de Defensa y de Agricultura, as\u00ed como de la Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD), del Instituto Nacional de Aguas Potables y Alcantarillados (INAPA) y de la Empresa de Generaci\u00f3n Hidroel\u00e9ctrica Dominicana (EGEHID).<\/p>\n\n\n\n<p>Respecto a las dem\u00e1s presas, el bolet\u00edn que ofrece diariamente el INDRHI indica que el embalse de Hatillo registra a la fecha 86.32 msnm; Bao con 322.99 msnm; Rinc\u00f3n con 121.38 msnm; Valdesia 148.69 msnm, y Jig\u00fcey registra un nivel de 539.43 msnm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El Instituto Nacional de Recursos Hidr\u00e1ulicos (INDRHI) inform\u00f3 que junto a las entidades competentes mantienen el monitoreo del agua captada en los principales embalses del pa\u00eds, enfatizando que actualmente las presas se encuentran en un buen nivel, y que solo en el embalse de Tavera est\u00e1n implementando medidas para llevarlo al nivel de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[751,282,1044,1010],"class_list":["post-2266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-empresas","tag-indhri","tag-monitoreo","tag-temporada-ciclonica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.- El Instituto Nacional de Recursos Hidr\u00e1ulicos (INDRHI) inform\u00f3 que junto a las entidades competentes mantienen el monitoreo del agua captada en los principales embalses del pa\u00eds, enfatizando que actualmente las presas se encuentran en un buen nivel, y que solo en el embalse de Tavera est\u00e1n implementando medidas para llevarlo al nivel de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-14T13:26:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-14T13:26:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/INDRHI-Fachada.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica\",\"datePublished\":\"2024-06-14T13:26:53+00:00\",\"dateModified\":\"2024-06-14T13:26:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/\"},\"wordCount\":392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/INDRHI-Fachada.jpeg\",\"keywords\":[\"Empresas\",\"Indhri\",\"Monitoreo\",\"Temporada Cicl\u00f3nica\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/\",\"name\":\"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/INDRHI-Fachada.jpeg\",\"datePublished\":\"2024-06-14T13:26:53+00:00\",\"dateModified\":\"2024-06-14T13:26:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/INDRHI-Fachada.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/INDRHI-Fachada.jpeg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/14\\\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/","og_locale":"es_ES","og_type":"article","og_title":"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica - Bombazo Informativo","og_description":"Santo Domingo.- El Instituto Nacional de Recursos Hidr\u00e1ulicos (INDRHI) inform\u00f3 que junto a las entidades competentes mantienen el monitoreo del agua captada en los principales embalses del pa\u00eds, enfatizando que actualmente las presas se encuentran en un buen nivel, y que solo en el embalse de Tavera est\u00e1n implementando medidas para llevarlo al nivel de...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-06-14T13:26:53+00:00","article_modified_time":"2024-06-14T13:26:54+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/INDRHI-Fachada.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica","datePublished":"2024-06-14T13:26:53+00:00","dateModified":"2024-06-14T13:26:54+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/"},"wordCount":392,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/INDRHI-Fachada.jpeg","keywords":["Empresas","Indhri","Monitoreo","Temporada Cicl\u00f3nica"],"articleSection":["Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/","name":"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/INDRHI-Fachada.jpeg","datePublished":"2024-06-14T13:26:53+00:00","dateModified":"2024-06-14T13:26:54+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/INDRHI-Fachada.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/INDRHI-Fachada.jpeg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/14\/indrhi-informa-que-mantienen-monitoreo-de-presas-ante-temporada-ciclonica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"INDRHI informa que mantienen monitoreo de presas ante temporada cicl\u00f3nica"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/INDRHI-Fachada.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2266"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2266\/revisions"}],"predecessor-version":[{"id":2267,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2266\/revisions\/2267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/1490"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}