{"id":2194,"date":"2024-06-11T10:48:35","date_gmt":"2024-06-11T14:48:35","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=2194"},"modified":"2024-06-11T10:48:36","modified_gmt":"2024-06-11T14:48:36","slug":"gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/","title":{"rendered":"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024"},"content":{"rendered":"\n<p>Santo Domingo.-\u00a0<strong>El presidente Luis Abinader<\/strong>\u00a0present\u00f3 este lunes los resultados del plan\u00a0<strong>\"Gan\u00e9mosle al Dengue\",\u00a0<\/strong>y dio a conocer las\u00a0<strong>acciones de respuesta<\/strong>\u00a0para enfrentar la\u00a0<strong>temporada cicl\u00f3nica<\/strong><\/p>\n\n\n\n<p><strong>Temporada cicl\u00f3nica 2024<\/strong><\/p>\n\n\n\n<p>El mandatario, al referirse al tema, manifest\u00f3 que&nbsp;<strong>se pronostic\u00f3<\/strong>&nbsp;que la actual temporada ser\u00e1&nbsp;<strong>una de las m\u00e1s activas.<\/strong><\/p>\n\n\n\n<p>En ese mismo sentido, sostuvo que el&nbsp;<strong>Centro Nacional de Pron\u00f3stico<\/strong>&nbsp;trabaja a toda hora para ofrecer&nbsp;<strong>informaciones confiables.<\/strong><\/p>\n\n\n\n<p><strong>Fases del plan<\/strong><\/p>\n\n\n\n<p>Refiri\u00f3 que para la&nbsp;<strong>temporada cicl\u00f3nica<\/strong>&nbsp;hay varias fases, que incluyen una&nbsp;<strong>campa\u00f1a para sensibilizar y orientar<\/strong>&nbsp;sobre fen\u00f3menos pronosticados y acciones preventivas.<\/p>\n\n\n\n<p>Tambi\u00e9n se llevan a cabo&nbsp;<strong>acciones estrat\u00e9gicas<\/strong>&nbsp;para atender las situaciones causadas por los&nbsp;<strong>eventos meteorol\u00f3gicos.<\/strong><\/p>\n\n\n\n<p>De esa misma manera, explic\u00f3 que se realiza una coordinaci\u00f3n de&nbsp;<strong>atenci\u00f3n y recuperaci\u00f3n<\/strong>&nbsp;para los afectados con el apoyo del gobierno central.<\/p>\n\n\n\n<p><strong>Directores del COE y Onamet<\/strong><\/p>\n\n\n\n<p>De su lado,&nbsp;<strong>los directores del COE, Juan Manuel M\u00e9ndez, y de Onamet, Gloria Ceballos<\/strong>, detallaron que el pa\u00eds cuenta con estaciones meteorol\u00f3gicas autom\u00e1ticas, radar Doppler integrado al mosaico de radares del Caribe; as\u00ed como el plan de&nbsp;<strong>campa\u00f1as de sensibilizaci\u00f3n, acciones estrat\u00e9gicas y de atenci\u00f3n.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.presidencia.gob.do\/sites\/default\/files\/inline-images\/592ecd8a-b7a6-4d4b-870a-fbf5681d4be2.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>Gan\u00e9mosle al Dengue<\/strong><\/p>\n\n\n\n<p>El segundo tema abordado en el encuentro estuvo a cargo del&nbsp;<strong>ministro de Salud P\u00fablica, V\u00edctor Atallah<\/strong>, quien asegur\u00f3 que el gobierno trabaja en el&nbsp;<strong>fortalecimiento&nbsp;<\/strong>de la capacidad del&nbsp;<strong>sistema de salud<\/strong>, lo que permitir\u00e1&nbsp;<strong>mitigar y reducir<\/strong>&nbsp;la incidencia de brotes, controlar los vectores e implementar una gesti\u00f3n central e intersectorial.<\/p>\n\n\n\n<p>En cuanto a la&nbsp;<strong>prevenci\u00f3n y control del dengue<\/strong>, Atallah inform\u00f3 que se eliminaron&nbsp;<strong>981,933<\/strong>&nbsp;recipientes, se deschatarrizaron&nbsp;<strong>280,098<\/strong>&nbsp;viviendas y se realizaron&nbsp;<strong>3,967<\/strong>&nbsp;fumigaciones.<\/p>\n\n\n\n<p>Asimismo, se encontraron&nbsp;<strong>497,731<\/strong>&nbsp;tanques con criaderos, se trataron&nbsp;<strong>453,888<\/strong>&nbsp;recipientes con larvicidas y se entregaron&nbsp;<strong>5,691<\/strong>&nbsp;mosquiteros.<\/p>\n\n\n\n<p><strong>Comparaci\u00f3n epidemiol\u00f3gica<\/strong><\/p>\n\n\n\n<p>Al referirse a casos confirmados, el ministro puntualiz\u00f3 que&nbsp;<strong>la Rep\u00fablica Dominicana<\/strong>&nbsp;es el&nbsp;<strong>tercer pa\u00eds con menos casos de dengue<\/strong>&nbsp;en la regi\u00f3n, con un total de&nbsp;<strong>840<\/strong>, siendo&nbsp;<strong>Puerto Rico y Costa Rica<\/strong>&nbsp;los dos pa\u00edses con menos casos confirmados.<\/p>\n\n\n\n<p>Mientras, otros nueve pa\u00edses superan los&nbsp;<strong>1,000 casos confirmados<\/strong>, encontr\u00e1ndose la mayor cantidad en&nbsp;<strong>Argentina, con 177,945.<\/strong><\/p>\n\n\n\n<p>En el territorio nacional, V\u00edctor Atallah agreg\u00f3 que,&nbsp;<strong>Santiago, La Vega, Moca, Puerto Plata, Nagua, San Francisco de Macor\u00eds y el Gran Santo Domingo<\/strong>&nbsp;son las provincias con mayores casos registrados.<\/p>\n\n\n\n<p>Mientras que las&nbsp;<strong>provincias con mayor riesgo<\/strong>&nbsp;son Puerto Plata, Montecristi, Santiago Rodr\u00edguez, Mar\u00eda Trinidad S\u00e1nchez, Duarte, Hermanas Mirabal, Monse\u00f1or Nouel, San Jos\u00e9 de Ocoa, San Juan y Barahona.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.-\u00a0El presidente Luis Abinader\u00a0present\u00f3 este lunes los resultados del plan\u00a0\"Gan\u00e9mosle al Dengue\",\u00a0y dio a conocer las\u00a0acciones de respuesta\u00a0para enfrentar la\u00a0temporada cicl\u00f3nica Temporada cicl\u00f3nica 2024 El mandatario, al referirse al tema, manifest\u00f3 que&nbsp;se pronostic\u00f3&nbsp;que la actual temporada ser\u00e1&nbsp;una de las m\u00e1s activas. En ese mismo sentido, sostuvo que el&nbsp;Centro Nacional de Pron\u00f3stico&nbsp;trabaja a toda hora&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[107,130,1010],"class_list":["post-2194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-luis-abinader","tag-presidente","tag-temporada-ciclonica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024 - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024 - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.-\u00a0El presidente Luis Abinader\u00a0present\u00f3 este lunes los resultados del plan\u00a0&quot;Gan\u00e9mosle al Dengue&quot;,\u00a0y dio a conocer las\u00a0acciones de respuesta\u00a0para enfrentar la\u00a0temporada cicl\u00f3nica Temporada cicl\u00f3nica 2024 El mandatario, al referirse al tema, manifest\u00f3 que&nbsp;se pronostic\u00f3&nbsp;que la actual temporada ser\u00e1&nbsp;una de las m\u00e1s activas. En ese mismo sentido, sostuvo que el&nbsp;Centro Nacional de Pron\u00f3stico&nbsp;trabaja a toda hora...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T14:48:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T14:48:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024\",\"datePublished\":\"2024-06-11T14:48:35+00:00\",\"dateModified\":\"2024-06-11T14:48:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/\"},\"wordCount\":499,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg\",\"keywords\":[\"Luis Abinader\",\"Presidente\",\"Temporada Cicl\u00f3nica\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/\",\"name\":\"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024 - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg\",\"datePublished\":\"2024-06-11T14:48:35+00:00\",\"dateModified\":\"2024-06-11T14:48:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/11\\\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024 - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024 - Bombazo Informativo","og_description":"Santo Domingo.-\u00a0El presidente Luis Abinader\u00a0present\u00f3 este lunes los resultados del plan\u00a0\"Gan\u00e9mosle al Dengue\",\u00a0y dio a conocer las\u00a0acciones de respuesta\u00a0para enfrentar la\u00a0temporada cicl\u00f3nica Temporada cicl\u00f3nica 2024 El mandatario, al referirse al tema, manifest\u00f3 que&nbsp;se pronostic\u00f3&nbsp;que la actual temporada ser\u00e1&nbsp;una de las m\u00e1s activas. En ese mismo sentido, sostuvo que el&nbsp;Centro Nacional de Pron\u00f3stico&nbsp;trabaja a toda hora...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-06-11T14:48:35+00:00","article_modified_time":"2024-06-11T14:48:36+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024","datePublished":"2024-06-11T14:48:35+00:00","dateModified":"2024-06-11T14:48:36+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/"},"wordCount":499,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg","keywords":["Luis Abinader","Presidente","Temporada Cicl\u00f3nica"],"articleSection":["Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/","name":"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024 - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg","datePublished":"2024-06-11T14:48:35+00:00","dateModified":"2024-06-11T14:48:36+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/11\/gobierno-dice-rd-esta-preparada-para-enfrentar-temporada-ciclonica-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Gobierno dice RD est\u00e1 preparada para enfrentar temporada cicl\u00f3nica 2024"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/a6ec7d59-6298-4b45-b1bf-b9f848dff55f.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2194"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2194\/revisions"}],"predecessor-version":[{"id":2196,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2194\/revisions\/2196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/2195"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}