{"id":2122,"date":"2024-06-05T10:13:16","date_gmt":"2024-06-05T14:13:16","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=2122"},"modified":"2024-06-05T10:13:17","modified_gmt":"2024-06-05T14:13:17","slug":"mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/","title":{"rendered":"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024"},"content":{"rendered":"\n<p>El Ministerio de Educaci\u00f3n de la Rep\u00fablica Dominicana (Minerd) anunci\u00f3 que los\u00a0<strong>d\u00edas 15, 16, 18 y 19 de junio se llevar\u00e1 a cabo la primera convocatoria de las Pruebas Nacionales 2024<\/strong>\u00a0para los estudiantes de nivel Secundario, B\u00e1sica y Media de la educaci\u00f3n de adultos.<\/p>\n\n\n\n<p>La instituci\u00f3n inst\u00f3 a m\u00e1s de 128 mil estudiantes del sistema educativo preuniversitario a que repasen los contenidos aprendidos en las aulas en las \u00e1reas de Matem\u00e1tica, Ciencias Sociales, Lengua Espa\u00f1ola y Ciencias de la Naturaleza.<\/p>\n\n\n\n<p>En esta convocatoria, a diferencia de a\u00f1os anteriores, los estudiantes del nivel Secundario tomar\u00e1n los ex\u00e1menes de dos asignaturas por d\u00eda.<\/p>\n\n\n\n<p>En esta convocatoria se aplicar\u00e1n dos pruebas por d\u00eda, una decisi\u00f3n que se fundamenta en estudios que ponen de manifiesto que los estudiantes alcanzan igual o mejor desempe\u00f1o que cuando se administra una sola prueba, adem\u00e1s de reducir el estr\u00e9s emocional que generan los ex\u00e1menes.<\/p>\n\n\n\n<p>Los alumnos de B\u00e1sica y Media de Adultos recibir\u00e1n sus pruebas de Matem\u00e1tica y Ciencias Sociales el d\u00eda 15 de junio; y el domingo 16, las pruebas de Lengua Espa\u00f1ola y Ciencias de la Naturaleza.<\/p>\n\n\n\n<p>Asimismo, los estudiantes del nivel Secundario en sus modalidades Acad\u00e9mica, T\u00e9cnico Profesional y en Artes ser\u00e1n evaluados el martes 18 de junio sobre Matem\u00e1tica y Ciencias Sociales y el mi\u00e9rcoles 19 de junio en Lengua Espa\u00f1ola y Ciencias de la Naturaleza, respectivamente.<\/p>\n\n\n\n<p>Las Pruebas Nacionales son evaluaciones estandarizadas que miden los aprendizajes de los estudiantes y aportan datos e informaciones para la toma de decisiones sobre pol\u00edtica de calidad de los aprendizajes del sistema educativo.<\/p>\n\n\n\n<p>Desde el a\u00f1o escolar pasado, m\u00e1s que contenidos curriculares, las Pruebas Nacionales eval\u00faan competencias, es decir, la aplicaci\u00f3n de lo aprendido.<\/p>\n\n\n\n<p>El Minerd inform\u00f3 que cada centro escolar debe informar al estudiante a cu\u00e1l escuela le corresponde asistir a examinarse, y que deben estar en el centro sede a las 8:00 de la ma\u00f1ana.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Educaci\u00f3n de la Rep\u00fablica Dominicana (Minerd) anunci\u00f3 que los\u00a0d\u00edas 15, 16, 18 y 19 de junio se llevar\u00e1 a cabo la primera convocatoria de las Pruebas Nacionales 2024\u00a0para los estudiantes de nivel Secundario, B\u00e1sica y Media de la educaci\u00f3n de adultos. La instituci\u00f3n inst\u00f3 a m\u00e1s de 128 mil estudiantes del sistema&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[145],"tags":[150,184,980],"class_list":["post-2122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-estudiantes","tag-minerd","tag-pruebas-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024 - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024 - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Educaci\u00f3n de la Rep\u00fablica Dominicana (Minerd) anunci\u00f3 que los\u00a0d\u00edas 15, 16, 18 y 19 de junio se llevar\u00e1 a cabo la primera convocatoria de las Pruebas Nacionales 2024\u00a0para los estudiantes de nivel Secundario, B\u00e1sica y Media de la educaci\u00f3n de adultos. La instituci\u00f3n inst\u00f3 a m\u00e1s de 128 mil estudiantes del sistema...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T14:13:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-05T14:13:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/img_2398-1-696x424-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024\",\"datePublished\":\"2024-06-05T14:13:16+00:00\",\"dateModified\":\"2024-06-05T14:13:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_2398-1-696x424-1.jpg\",\"keywords\":[\"Estudiantes\",\"Minerd\",\"Pruebas Nacionales\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/\",\"name\":\"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024 - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_2398-1-696x424-1.jpg\",\"datePublished\":\"2024-06-05T14:13:16+00:00\",\"dateModified\":\"2024-06-05T14:13:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_2398-1-696x424-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_2398-1-696x424-1.jpg\",\"width\":696,\"height\":424},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/06\\\/05\\\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024 - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024 - Bombazo Informativo","og_description":"El Ministerio de Educaci\u00f3n de la Rep\u00fablica Dominicana (Minerd) anunci\u00f3 que los\u00a0d\u00edas 15, 16, 18 y 19 de junio se llevar\u00e1 a cabo la primera convocatoria de las Pruebas Nacionales 2024\u00a0para los estudiantes de nivel Secundario, B\u00e1sica y Media de la educaci\u00f3n de adultos. La instituci\u00f3n inst\u00f3 a m\u00e1s de 128 mil estudiantes del sistema...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-06-05T14:13:16+00:00","article_modified_time":"2024-06-05T14:13:17+00:00","og_image":[{"width":696,"height":424,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/img_2398-1-696x424-1.jpg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024","datePublished":"2024-06-05T14:13:16+00:00","dateModified":"2024-06-05T14:13:17+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/img_2398-1-696x424-1.jpg","keywords":["Estudiantes","Minerd","Pruebas Nacionales"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/","name":"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024 - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/img_2398-1-696x424-1.jpg","datePublished":"2024-06-05T14:13:16+00:00","dateModified":"2024-06-05T14:13:17+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/img_2398-1-696x424-1.jpg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/img_2398-1-696x424-1.jpg","width":696,"height":424},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/06\/05\/mas-de-128-mil-estudiantes-son-llamados-a-participar-en-las-pruebas-nacionales-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 128 mil estudiantes son llamados a participar en las pruebas nacionales 2024"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/06\/img_2398-1-696x424-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=2122"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2122\/revisions"}],"predecessor-version":[{"id":2124,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/2122\/revisions\/2124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/2123"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=2122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=2122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=2122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}