{"id":1801,"date":"2024-05-13T08:39:12","date_gmt":"2024-05-13T12:39:12","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=1801"},"modified":"2024-05-13T08:39:13","modified_gmt":"2024-05-13T12:39:13","slug":"abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/","title":{"rendered":"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds"},"content":{"rendered":"\n<p>Santo Domingo.-  El Partido Revolucionario Moderno (PRM) cerr\u00f3 de manera contundente la campa\u00f1a a nivel nacional, con grandes caravanas, que encabez\u00f3 el candidato presidencial, Luis Abinader, en Santo Domingo, y la dirigencia del partido en todas las provincias, sellando el triunfo para las elecciones del pr\u00f3ximo 19 de mayo.<\/p>\n\n\n\n<p>El mandatario inici\u00f3 pasadas las 11 de la ma\u00f1ana un extenso recorrido por Los Alcarrizos, donde recibi\u00f3 el apoyo del municipio junto al senador y candidato de la provincia Santo Domingo, Antonio Taveras, as\u00ed como los candidatos a diputados.<\/p>\n\n\n\n<p>Pasado el mediod\u00eda, Abinader entr\u00f3 en marcha caravana a Santo Domingo Oeste junto al senador Taveras, donde la gente se tir\u00f3 a las calles para declarar que el Cambio sigue para bien del pa\u00eds.<\/p>\n\n\n\n<p>Entrada la tarde, Abinader culmin\u00f3 sus recorridos de cierre con una marcha caravana en Santo Domingo Este, en la que qued\u00f3 claro por qu\u00e9 lidera con m\u00e1s de un 60% las encuestas y el PRM ganar\u00e1 rotundamente la provincia Santo Domingo en todos los niveles.<\/p>\n\n\n\n<p>La vicepresidenta Raquel Pe\u00f1a recibi\u00f3 el apoyo de la gente de Dajab\u00f3n, recorriendo las calles junto al candidato a senador Ney Rodr\u00edguez.<\/p>\n\n\n\n<p>En la tarde, encabez\u00f3 la caravana del cambio que sigue junto a la senadora Ginette Bournigal y el presidente del PRM, Jos\u00e9 Ignacio Paliza en Puerto Plata.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"696\" height=\"464\" src=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/e9f3c2b5-7360-4c79-bdbd-671069585d6a.webp\" alt=\"\" class=\"wp-image-1803\" srcset=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/e9f3c2b5-7360-4c79-bdbd-671069585d6a.webp 696w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/e9f3c2b5-7360-4c79-bdbd-671069585d6a-300x200.webp 300w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/e9f3c2b5-7360-4c79-bdbd-671069585d6a-600x400.webp 600w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/figure>\n\n\n\n<p>La secretaria general, Carolina Mej\u00eda, lider\u00f3 en la las caravanas de desbordante apoyo al candidato a senador de Monse\u00f1or Nouel, H\u00e9ctor Acosta, en la ma\u00f1ana, y en la tarde la del candidato a senador de La Vega, Ram\u00f3n Rogelio Genao.<\/p>\n\n\n\n<p>Alfredo Pacheco, presidente de la C\u00e1mara de Diputados, lider\u00f3 junto al candidato a senador Guillermo Moreno, una caravana por sectores populares, sellando el triunfo del PRM en el Distrito Nacional.<\/p>\n\n\n\n<p>El miembro de la Direcci\u00f3n Ejecutiva, David Collado, estuvo en Monte Plata, acompa\u00f1ado al candidato a senador Pedro Tineo.<\/p>\n\n\n\n<p>El secretario de finanzas, Eduardo Sanz Lovat\u00f3n, encabez\u00f3 una caravana en la que la militancia y simpatizantes desafiaron la lluvia para mostrar su apoyo al pr\u00f3ximo senador, Rafael Bar\u00f3n Duluc, (Cholit\u00edn).<\/p>\n\n\n\n<p>Ricardo De los Santos, presidente del Senado, march\u00f3 por las calles de Cotu\u00ed, donde los cotuisanos lo reafirmaron como el senador que sigue en S\u00e1nchez Ram\u00edrez.<\/p>\n\n\n\n<p>El secretario de organizaci\u00f3n, Deligne Ascensi\u00f3n, comand\u00f3 las tropos que desfilaron por las calles de San Crist\u00f3bal en apoyo al candidato a senador Gustavo Lara.<\/p>\n\n\n\n<p>El miembro de la direcci\u00f3n ejecutiva V\u00edctor Ito Bison\u00f3 lider\u00f3 la marcha caravana de Hato Mayor, con el candidato a senador victorioso Crist\u00f3bal Castillo.<\/p>\n\n\n\n<p>Wellington Arnaud encabez\u00f3 una marcha caravana junto al candidato a senador de Barahona, Mois\u00e9s Ayala, recibiendo apoyo de la gente en las calles.<\/p>\n\n\n\n<p>Faride Raful, coordinadora de campa\u00f1a encabez\u00f3 la marcha caravana de Mao, con el candidato a senador Odalis Rodr\u00edguez.<\/p>\n\n\n\n<p>Al delegado ante la Junta Central Electoral, Sigmund Freund, le correspondi\u00f3 dirigir la caravana de Pedernales, en apoyo al candidato a senador Augusto Vel\u00e1zquez.<\/p>\n\n\n\n<p>Roberto \u00c1ngel Salcedo encabez\u00f3 la caravana del triunfo en San Jos\u00e9 de Ocoa, con el candidato y pr\u00f3ximo senador, Aneudy Ort\u00edz Saji\u00fan, y los candidatos a diputados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"696\" height=\"466\" src=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/48091fb2-51ef-4164-ac22-d7b061c5af09.webp\" alt=\"\" class=\"wp-image-1804\" srcset=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/48091fb2-51ef-4164-ac22-d7b061c5af09.webp 696w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/48091fb2-51ef-4164-ac22-d7b061c5af09-300x200.webp 300w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/figure>\n\n\n\n<p>En Nueva York, estuvieron Eligio J\u00e1quez y Neftal\u00ed Fuertes, secretario de los dominicanos en el Exterior.<\/p>\n\n\n\n<p>Cierres el s\u00e1bado<\/p>\n\n\n\n<p>El s\u00e1bado, Abinader cerr\u00f3 la campa\u00f1a en el Distrito Nacional, en un acto de masas en el pabell\u00f3n de voleibol junto al candidato a senador Guillermo Moreno.<\/p>\n\n\n\n<p>En la tarde, cerr\u00f3 con una exitosa caravana en Santiago con el candidato a senador Daniel Rivera.<\/p>\n\n\n\n<p>En San Pedro de Macor\u00eds cerr\u00f3 la campa\u00f1a Nelson Arroyo, junto a la candidata a senadora Aracelis Villanueva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El Partido Revolucionario Moderno (PRM) cerr\u00f3 de manera contundente la campa\u00f1a a nivel nacional, con grandes caravanas, que encabez\u00f3 el candidato presidencial, Luis Abinader, en Santo Domingo, y la dirigencia del partido en todas las provincias, sellando el triunfo para las elecciones del pr\u00f3ximo 19 de mayo. El mandatario inici\u00f3 pasadas las 11&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[39,32,26,107,29,27],"class_list":["post-1801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-campana","tag-candidato","tag-elecciones","tag-luis-abinader","tag-prm","tag-voto2024"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.- El Partido Revolucionario Moderno (PRM) cerr\u00f3 de manera contundente la campa\u00f1a a nivel nacional, con grandes caravanas, que encabez\u00f3 el candidato presidencial, Luis Abinader, en Santo Domingo, y la dirigencia del partido en todas las provincias, sellando el triunfo para las elecciones del pr\u00f3ximo 19 de mayo. El mandatario inici\u00f3 pasadas las 11...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-13T12:39:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-13T12:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"656\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds\",\"datePublished\":\"2024-05-13T12:39:12+00:00\",\"dateModified\":\"2024-05-13T12:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp\",\"keywords\":[\"Campa\u00f1a\",\"Candidato\",\"Elecciones\",\"Luis Abinader\",\"PRM\",\"Voto2024\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/\",\"name\":\"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp\",\"datePublished\":\"2024-05-13T12:39:12+00:00\",\"dateModified\":\"2024-05-13T12:39:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp\",\"width\":696,\"height\":656},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/05\\\/13\\\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/","og_locale":"es_ES","og_type":"article","og_title":"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds - Bombazo Informativo","og_description":"Santo Domingo.- El Partido Revolucionario Moderno (PRM) cerr\u00f3 de manera contundente la campa\u00f1a a nivel nacional, con grandes caravanas, que encabez\u00f3 el candidato presidencial, Luis Abinader, en Santo Domingo, y la dirigencia del partido en todas las provincias, sellando el triunfo para las elecciones del pr\u00f3ximo 19 de mayo. El mandatario inici\u00f3 pasadas las 11...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-05-13T12:39:12+00:00","article_modified_time":"2024-05-13T12:39:13+00:00","og_image":[{"width":696,"height":656,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp","type":"image\/webp"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds","datePublished":"2024-05-13T12:39:12+00:00","dateModified":"2024-05-13T12:39:13+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp","keywords":["Campa\u00f1a","Candidato","Elecciones","Luis Abinader","PRM","Voto2024"],"articleSection":["Pol\u00edtica"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/","name":"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp","datePublished":"2024-05-13T12:39:12+00:00","dateModified":"2024-05-13T12:39:13+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp","width":696,"height":656},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/05\/13\/abinader-y-candidatos-del-prm-reciben-apoyo-masivo-durante-cierre-de-campana-en-todo-el-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Abinader y candidatos del PRM reciben apoyo masivo durante cierre de campa\u00f1a en todo el pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/05\/2f01e86e-536c-4f03-9ee4-271adcb808ce.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1801"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1801\/revisions"}],"predecessor-version":[{"id":1805,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1801\/revisions\/1805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/1802"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}