{"id":1633,"date":"2024-04-26T11:18:32","date_gmt":"2024-04-26T15:18:32","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=1633"},"modified":"2024-04-26T11:18:32","modified_gmt":"2024-04-26T15:18:32","slug":"caribbean-cinemas-adquiere-activos-de-palacio-del-cine","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/","title":{"rendered":"Caribbean Cinemas adquiere activos de Palacio del Cine"},"content":{"rendered":"\n<p>Luego de cordiales conversaciones, los ejecutivos de las empresas Caribbean Cinemas y Wometco Dominicana arribaron a un acuerdo, por medio del cual Caribbean Cinemas adquiri\u00f3 los activos operativos de varias salas de cine que se encontraban operando bajo la marca Palacio del Cine en el pa\u00eds.<\/p>\n\n\n\n<p>A trav\u00e9s de esta transacci\u00f3n, Caribbean Cinemas ampl\u00eda sus operaciones en el pa\u00eds a trav\u00e9s de la incorporaci\u00f3n de las salas de cine del centro comercial Sambil, uno de los principales de la ciudad de Santo Domingo, y en algunas semanas iniciar\u00e1 la operaci\u00f3n de Multiplaza Higuey, en la provincia La Altagracia.<\/p>\n\n\n\n<p>Robert Carrady y Gregory Quinn, ejecutivos de Caribbean Cinemas, expresaron a trav\u00e9s de un comunicado enviado a Diario Libre que esta transacci\u00f3n es una nueva muestra del compromiso de la marca, la cual ha operado de forma continua en la Rep\u00fablica Dominicana por m\u00e1s de 48 a\u00f1os, adem\u00e1s de contar con m\u00e1s de 600 pantallas de cine en 15 pa\u00edses de la regi\u00f3n.<\/p>\n\n\n\n<p>Indicaron igualmente que \u201cesta ampliaci\u00f3n de nuestras operaciones en el pa\u00eds continuar\u00e1 orientada a respaldar las producciones cinematogr\u00e1ficas locales, de la mano con los productores dominicanos, quienes seguir\u00e1n contando con m\u00e1s y mejores pantallas para a ofrecer al p\u00fablico dominicano experiencias cinematogr\u00e1ficas memorables, de clase mundial\u201d.<\/p>\n\n\n\n<p>Por su parte, Wometco Dominicana, operadora de las salas de cine Palacio del Cine, fue pionera en apoyo a las producciones locales, como parte de un grupo de empresas dedicadas al entretenimiento y restaurantes.<\/p>\n\n\n\n<p><strong>Expansi\u00f3n internacionalizaci\u00f3n<\/strong><br>Adem\u00e1s de Rep\u00fablica Dominicana, han extendido sus operaciones Puerto Rico, Colombia, M\u00e9xico y pr\u00f3ximamente en Panam\u00e1, a lo que dedicar\u00e1 su enfoque, luego de haber realizado esta transacci\u00f3n.<\/p>\n\n\n\n<p>Finalmente, los ejecutivos de ambas empresas coincidieron en la importancia del fortalecimiento de las salas de cine como un componente esencial del crecimiento de la industria cinematogr\u00e1fica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de cordiales conversaciones, los ejecutivos de las empresas Caribbean Cinemas y Wometco Dominicana arribaron a un acuerdo, por medio del cual Caribbean Cinemas adquiri\u00f3 los activos operativos de varias salas de cine que se encontraban operando bajo la marca Palacio del Cine en el pa\u00eds. A trav\u00e9s de esta transacci\u00f3n, Caribbean Cinemas ampl\u00eda sus&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[79,799,798,800],"class_list":["post-1633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula","tag-activos","tag-caribbean-cinemas","tag-cine","tag-palacio-del-cine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caribbean Cinemas adquiere activos de Palacio del Cine - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caribbean Cinemas adquiere activos de Palacio del Cine - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Luego de cordiales conversaciones, los ejecutivos de las empresas Caribbean Cinemas y Wometco Dominicana arribaron a un acuerdo, por medio del cual Caribbean Cinemas adquiri\u00f3 los activos operativos de varias salas de cine que se encontraban operando bajo la marca Palacio del Cine en el pa\u00eds. A trav\u00e9s de esta transacci\u00f3n, Caribbean Cinemas ampl\u00eda sus...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T15:18:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"591\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Caribbean Cinemas adquiere activos de Palacio del Cine\",\"datePublished\":\"2024-04-26T15:18:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/\"},\"wordCount\":335,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp\",\"keywords\":[\"Activos\",\"Caribbean Cinemas\",\"Cine\",\"Palacio del Cine\"],\"articleSection\":[\"Far\u00e1ndula\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/\",\"name\":\"Caribbean Cinemas adquiere activos de Palacio del Cine - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp\",\"datePublished\":\"2024-04-26T15:18:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp\",\"width\":1080,\"height\":591},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/04\\\/26\\\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caribbean Cinemas adquiere activos de Palacio del Cine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caribbean Cinemas adquiere activos de Palacio del Cine - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/","og_locale":"es_ES","og_type":"article","og_title":"Caribbean Cinemas adquiere activos de Palacio del Cine - Bombazo Informativo","og_description":"Luego de cordiales conversaciones, los ejecutivos de las empresas Caribbean Cinemas y Wometco Dominicana arribaron a un acuerdo, por medio del cual Caribbean Cinemas adquiri\u00f3 los activos operativos de varias salas de cine que se encontraban operando bajo la marca Palacio del Cine en el pa\u00eds. A trav\u00e9s de esta transacci\u00f3n, Caribbean Cinemas ampl\u00eda sus...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-04-26T15:18:32+00:00","og_image":[{"width":1080,"height":591,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp","type":"image\/webp"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Caribbean Cinemas adquiere activos de Palacio del Cine","datePublished":"2024-04-26T15:18:32+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/"},"wordCount":335,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp","keywords":["Activos","Caribbean Cinemas","Cine","Palacio del Cine"],"articleSection":["Far\u00e1ndula"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/","name":"Caribbean Cinemas adquiere activos de Palacio del Cine - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp","datePublished":"2024-04-26T15:18:32+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp","width":1080,"height":591},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/04\/26\/caribbean-cinemas-adquiere-activos-de-palacio-del-cine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Caribbean Cinemas adquiere activos de Palacio del Cine"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/04\/1A1A1E3D-599A-4F75-8BAA-9012B46591FB.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1633"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1633\/revisions"}],"predecessor-version":[{"id":1635,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1633\/revisions\/1635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/1634"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}