{"id":1358,"date":"2024-03-29T09:44:26","date_gmt":"2024-03-29T13:44:26","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=1358"},"modified":"2024-03-29T09:50:42","modified_gmt":"2024-03-29T13:50:42","slug":"el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/","title":{"rendered":"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez"},"content":{"rendered":"\n<p>La materia prima m\u00e1s alcista de este a\u00f1o sigue batiendo r\u00e9cords. El cacao est\u00e1 liderando las subidas de los recursos b\u00e1sicos, con mucha diferencia frente al resto: el precio del grano sube un 135% en lo que va de a\u00f1o y&nbsp;<strong>acaba de batir los 10.000 d\u00f3lares la tonelada por primera vez en la historia.<\/strong>&nbsp;Este rally mete\u00f3rico&nbsp;tiene su origen en las malas perspectivas para las cosechas en Costa de Marfil y Ghana, dos pa\u00edses responsables de casi el 60% de la oferta mundial de cacao, y las perspectivas no son nada positivas para el futuro. La subida de precio ha llevado al recurso agr\u00edcola a superar, por primera vez desde 2003, los precios de uno de los metales industriales m\u00e1s codiciados en este momento, por su importancia en el desarrollo del veh\u00edculo el\u00e9ctrico y las redes de carga: el cobre.<\/p>\n\n\n\n<p>S\u00f3lo en marzo, los futuros sobre el precio del cacao se han encarecido un 50%.&nbsp;La mala cosecha en \u00c1frica Occidental&nbsp;sigue sin dar tregua, con las plantaciones en Costa de Marfil y Ghana, que suponen m\u00e1s del 55% de la oferta mundial, sufriendo las condiciones climatol\u00f3gicas adversas para la cosecha, adem\u00e1s de una enfermedad que est\u00e1 deteriorando la producci\u00f3n del grano. En este contexto el precio no para de subir, hasta el punto de que&nbsp;<strong>ya ha batido los 10.000 d\u00f3lares la tonelada por primera vez en la historia.<\/strong><\/p>\n\n\n\n<p>Con una subida de precio anual que ya supera el 135%, el cacao lidera el r\u00e1nking de las materias primas que m\u00e1s se encarecen del planeta, y con mucha diferencia: tras ella se mantiene la gasolina, con una subida de m\u00e1s del 30% desde el primer d\u00eda del ejercicio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"948\" height=\"465\" src=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg\" alt=\"\" class=\"wp-image-1359\" srcset=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg 948w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1-300x147.jpeg 300w, https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1-768x377.jpeg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/figure>\n\n\n\n<p>El aumento de precios del cacao se est\u00e1 dejando sentir en el principal alimento que lo utiliza como materia prima: el chocolate. La analista de\u00a0<em>Bloomberg<\/em>, Diana Gomes, avisa de que \"los precios del chocolate van a ser todav\u00eda m\u00e1s caros en la Pascua de 2025, si el clima y las enfermedades de las plantas prolongan el d\u00e9ficit de producci\u00f3n\", algo que, para muchos analistas, es probable que contin\u00fae ocurriendo.<\/p>\n\n\n\n<p>Las subidas han sido tan agresivas que han llevado al cacao a superar el precio del cobre por primera vez desde 2003. Entonces, una enorme sobreoferta de cobre hundi\u00f3 los precios del metal hasta caer por debajo de los del cacao, pero ahora la situaci\u00f3n est\u00e1 siendo la opuesta:&nbsp;<strong>si a principios de a\u00f1o la tonelada de cobre era el doble de cara que la del cacao, ahora ya cuesta m\u00e1s el grano que el metal.<\/strong><\/p>\n\n\n\n<p>Los mercados est\u00e1n pendientes de ver c\u00f3mo ser\u00e1 la cosecha de cacao de mitad de a\u00f1o (el grano se recolecta en dos momentos diferentes, siendo la de verano la cosecha m\u00e1s peque\u00f1a de las dos), y las perspectivas, seg\u00fan ha anunciado Costa de Marfil, no son nada positivas.&nbsp;<strong>El rally que est\u00e1 viviendo el cacao en el corto plazo est\u00e1 siendo impulsado por los compradores f\u00edsicos de la materia prima<\/strong>, y no tanto por los especuladores, ya que el n\u00famero de contratos en vigor sobre el futuro de la materia prima no ha parado de caer desde enero.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>A principios de a\u00f1o el cobre costaba m\u00e1s del doble que el cacao y la situaci\u00f3n se ha dado la vuelta<\/p>\n<\/blockquote>\n\n\n\n<p>En Europa, adem\u00e1s, el problema est\u00e1 siendo especialmente grave, con el diferencial de precios del cacao ampli\u00e1ndose frente a las referencias estadounidenses debido a la nueva regulaci\u00f3n sobre algunas materias primas que ha adoptado la Uni\u00f3n. Seg\u00fan la norma, en 2025 no se podr\u00e1n vender granos de cacao que provengan de \"terrenos deforestados\", una imposici\u00f3n que est\u00e1 dando dolores de cabeza a los productores y que est\u00e1 contribuyendo a aumentar los precios de la materia prima en el Viejo Continente por encima de las subidas, de por s\u00ed ya mete\u00f3ricas.<\/p>\n\n\n\n<p>Fuente: El Economista<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La materia prima m\u00e1s alcista de este a\u00f1o sigue batiendo r\u00e9cords. El cacao est\u00e1 liderando las subidas de los recursos b\u00e1sicos, con mucha diferencia frente al resto: el precio del grano sube un 135% en lo que va de a\u00f1o y&nbsp;acaba de batir los 10.000 d\u00f3lares la tonelada por primera vez en la historia.&nbsp;Este rally&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[691,693,692],"class_list":["post-1358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-cacao","tag-mundo","tag-precios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"La materia prima m\u00e1s alcista de este a\u00f1o sigue batiendo r\u00e9cords. El cacao est\u00e1 liderando las subidas de los recursos b\u00e1sicos, con mucha diferencia frente al resto: el precio del grano sube un 135% en lo que va de a\u00f1o y&nbsp;acaba de batir los 10.000 d\u00f3lares la tonelada por primera vez en la historia.&nbsp;Este rally...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-29T13:44:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-29T13:50:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez\",\"datePublished\":\"2024-03-29T13:44:26+00:00\",\"dateModified\":\"2024-03-29T13:50:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/\"},\"wordCount\":703,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/63f751ba5e7c1.jpeg\",\"keywords\":[\"Cacao\",\"Mundo\",\"Precios\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/\",\"name\":\"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/63f751ba5e7c1.jpeg\",\"datePublished\":\"2024-03-29T13:44:26+00:00\",\"dateModified\":\"2024-03-29T13:50:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/63f751ba5e7c1.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/63f751ba5e7c1.jpeg\",\"width\":948,\"height\":465},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/29\\\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/","og_locale":"es_ES","og_type":"article","og_title":"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez - Bombazo Informativo","og_description":"La materia prima m\u00e1s alcista de este a\u00f1o sigue batiendo r\u00e9cords. El cacao est\u00e1 liderando las subidas de los recursos b\u00e1sicos, con mucha diferencia frente al resto: el precio del grano sube un 135% en lo que va de a\u00f1o y&nbsp;acaba de batir los 10.000 d\u00f3lares la tonelada por primera vez en la historia.&nbsp;Este rally...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-03-29T13:44:26+00:00","article_modified_time":"2024-03-29T13:50:42+00:00","og_image":[{"width":948,"height":465,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez","datePublished":"2024-03-29T13:44:26+00:00","dateModified":"2024-03-29T13:50:42+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/"},"wordCount":703,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg","keywords":["Cacao","Mundo","Precios"],"articleSection":["Econom\u00eda"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/","name":"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg","datePublished":"2024-03-29T13:44:26+00:00","dateModified":"2024-03-29T13:50:42+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg","width":948,"height":465},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/29\/el-cacao-ya-es-mas-caro-que-el-cobre-la-tonelada-bate-los-10-000-dolares-por-primera-vez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"El cacao ya es m\u00e1s caro que el cobre: la tonelada bate los 10.000 d\u00f3lares por primera vez"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/63f751ba5e7c1.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1358"}],"version-history":[{"count":3,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1358\/revisions"}],"predecessor-version":[{"id":1362,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1358\/revisions\/1362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/1359"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}