{"id":1136,"date":"2024-03-05T11:28:37","date_gmt":"2024-03-05T15:28:37","guid":{"rendered":"https:\/\/bombazoinformativo.com\/?p=1136"},"modified":"2024-03-05T11:28:37","modified_gmt":"2024-03-05T15:28:37","slug":"abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019","status":"publish","type":"post","link":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/","title":{"rendered":"Abinader: Embarazos en adolescentes descienden  9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019"},"content":{"rendered":"\n<p>Santo Domingo.-&nbsp;<strong>El presidente Luis Abinader&nbsp;<\/strong>resalt\u00f3 este lunes los logros alcanzados por el Gobierno,&nbsp;<strong>con respecto a la mujer<\/strong>, destacando que los&nbsp;<strong>embarazos en adolescentes<\/strong>&nbsp;pasaron de 32,061 en el a\u00f1o 2019 a&nbsp;<strong>23,070 en el a\u00f1o 2023.<\/strong><\/p>\n\n\n\n<p>De igual modo, resalt\u00f3 que las exportaciones de&nbsp;<strong>empresas lideradas por mujeres<\/strong>&nbsp;desde el 2020 al 2023 superaron&nbsp;<strong>m\u00e1s de 7,295 millones de d\u00f3lares.<\/strong><\/p>\n\n\n\n<p>Estas declaraciones las ofreci\u00f3 el jefe de Estado durante&nbsp;<strong>LA Semanal<\/strong>, celebrada en el Sal\u00f3n Las Cari\u00e1tides del&nbsp;<strong>Palacio Nacional.<\/strong><\/p>\n\n\n\n<p><strong>Ministerio de la Mujer<\/strong><\/p>\n\n\n\n<p>En cuanto a la labor de&nbsp;<strong>prevenci\u00f3n y atenci\u00f3n<\/strong>&nbsp;a la violencia, inform\u00f3 que el&nbsp;<strong>Ministerio de la Mujer<\/strong>&nbsp;ha llegado a&nbsp;<strong>390,733 viviendas<\/strong>&nbsp;con jornadas&nbsp;<strong>\"Puerta a Puerta\",&nbsp;<\/strong>para promover una&nbsp;<strong>vida libre de violencia<\/strong>&nbsp;en todo el pa\u00eds. Como resultado,&nbsp;<strong>2,881,261 personas<\/strong>&nbsp;han sido&nbsp;<strong>orientadas y sensibilizadas<\/strong>, siendo el&nbsp;<strong>43 %<\/strong>&nbsp;hombres y el&nbsp;<strong>57 %<\/strong>&nbsp;mujeres.&nbsp;<\/p>\n\n\n\n<p><strong>Casas de acogida<\/strong><\/p>\n\n\n\n<p>Respecto al incremento en capacidad de respuesta, el jefe de Estado mencion\u00f3 que&nbsp;<strong>5,065 mujeres<\/strong>&nbsp;y sus dependientes fueron protegidas en&nbsp;<strong>casas de acogida<\/strong>, las cuales han&nbsp;<strong>aumentado de 3 a 17&nbsp;<\/strong>durante su gesti\u00f3n, incluyendo una especializada en tr\u00e1fico y trata, otra en embarazo de adolescentes y un centro nacional con capacidad para&nbsp;<strong>200 mujeres<\/strong>&nbsp;y sus familias.<\/p>\n\n\n\n<p><strong>Programa de apoyo econ\u00f3mico y atenci\u00f3n a la di\u00e1spora<\/strong><\/p>\n\n\n\n<p>En cuanto a acciones espec\u00edficas para mujeres afectadas, el presidente anunci\u00f3 que&nbsp;<strong>por primera vez<\/strong>&nbsp;se estableci\u00f3 un programa de apoyo econ\u00f3mico de&nbsp;<strong>RD 10,000<\/strong>&nbsp;mensuales para mujeres en condiciones de riesgo, as\u00ed como un programa de&nbsp;<strong>atenci\u00f3n a la di\u00e1spora<\/strong>, brindando servicios de atenci\u00f3n telef\u00f3nica para asistencia&nbsp;<strong>psicol\u00f3gica y legal.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.presidencia.gob.do\/sites\/default\/files\/inline-images\/WhatsApp%20Image%202024-03-04%20at%207.49.22%20PM.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>La l\u00ednea de emergencia *212<\/strong><\/p>\n\n\n\n<p>La&nbsp;<strong>l\u00ednea de emergencia *212<\/strong>&nbsp;se ha extendido a todas las provincias del pa\u00eds, con un total de&nbsp;<strong>28,166<\/strong>&nbsp;atenciones,&nbsp;<strong>468&nbsp;<\/strong>rescates,&nbsp;<strong>236,322<\/strong>&nbsp;atenciones legales y&nbsp;<strong>102,849<\/strong>&nbsp;consultas psicol\u00f3gicas ofrecidas&nbsp;<strong>hasta 2023.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Bono Mujer y la Escuela Nacional de la Igualdad<\/strong><\/p>\n\n\n\n<p>Adem\u00e1s, se ha invertido&nbsp;<strong>RD 24,495,00<\/strong>&nbsp;en el Bono Mujer, para facilitar el acceso a la vivienda.<\/p>\n\n\n\n<p>Igualmente, el jefe de Estado anunci\u00f3 la apertura de la&nbsp;<strong>Escuela Nacional de la Igualdad,<\/strong>&nbsp;en honor a la activista&nbsp;<strong>Magaly Pineda.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Pro Dominicana&nbsp;<\/strong><\/p>\n\n\n\n<p>Destac\u00f3 los logros de&nbsp;<strong>Pro Dominicana<\/strong>&nbsp;en el sector empresarial, con&nbsp;<strong>12 reconocimientos<\/strong>&nbsp;a empresas lideradas por<strong>&nbsp;mujeres exportadoras<\/strong>&nbsp;y un total de&nbsp;<strong>7,295 millones<\/strong>&nbsp;de exportaciones durante&nbsp;<strong>2020-2023<\/strong>.<\/p>\n\n\n\n<p>En cuanto a indicadores sociales, el \u00edndice de pobreza extrema en hogares liderados por mujeres ha alcanzado un&nbsp;<strong>r\u00e9cord m\u00ednimo<\/strong>&nbsp;de 2.41 en 2023.&nbsp;<\/p>\n\n\n\n<p><strong>Industria y Comercio<\/strong><\/p>\n\n\n\n<p>El presidente tambi\u00e9n habl\u00f3 sobre la certificaci\u00f3n&nbsp;<strong>Mipymes Mujer<\/strong>, con acceso a licitaciones exclusivas y otros incentivos, y mencion\u00f3 que el&nbsp;<strong>53 % del empleo<\/strong>&nbsp;en zonas francas corresponde a mujeres, as\u00ed como el&nbsp;<strong>61.4 %<\/strong>&nbsp;de la cartera de pr\u00e9stamos en&nbsp;<strong>Promipyme.<\/strong><\/p>\n\n\n\n<p><strong>Sup\u00e9rate<\/strong><\/p>\n\n\n\n<p>El programa&nbsp;<strong>Mujeres Super Emprendedoras,<\/strong>&nbsp;a trav\u00e9s de Sup\u00e9rate, ha llevado&nbsp;<strong>964 proyectos<\/strong>&nbsp;liderados por mujeres, con&nbsp;<strong>acompa\u00f1amiento y capacitaciones socioeducativas<\/strong>&nbsp;para mujeres que aspiran iniciar un&nbsp;<strong>microemprendimiento<\/strong>, para mejorar su condici\u00f3n de vida.<\/p>\n\n\n\n<p><strong>Gabinete de Adolescencia y Ni\u00f1ez de la Primera Dama<\/strong><\/p>\n\n\n\n<p>La&nbsp;<strong>Oficina de la Primera Dama<\/strong>&nbsp;ha registrado un&nbsp;<strong>aumento del 72 %<\/strong>&nbsp;en llamadas al centro de contacto&nbsp;<strong>\"Cuida tu salud mental\"<\/strong>&nbsp;y m\u00e1s de 355 jornadas de&nbsp;<strong>detecci\u00f3n oportuna<\/strong>&nbsp;de c\u00e1nceres de mama y cervicouterino, concienciando a m\u00e1s de&nbsp;<strong>53,000 mujeres<\/strong>&nbsp;en prevenci\u00f3n oportuna.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, ha habido una&nbsp;<strong>disminuci\u00f3n significativa<\/strong>&nbsp;en los embarazos en adolescentes, pasando de&nbsp;<strong>32,061&nbsp;<\/strong>en 2019 a&nbsp;<strong>23,070 en 2023.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.-&nbsp;El presidente Luis Abinader&nbsp;resalt\u00f3 este lunes los logros alcanzados por el Gobierno,&nbsp;con respecto a la mujer, destacando que los&nbsp;embarazos en adolescentes&nbsp;pasaron de 32,061 en el a\u00f1o 2019 a&nbsp;23,070 en el a\u00f1o 2023. De igual modo, resalt\u00f3 que las exportaciones de&nbsp;empresas lideradas por mujeres&nbsp;desde el 2020 al 2023 superaron&nbsp;m\u00e1s de 7,295 millones de d\u00f3lares. Estas&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[562,561,468,107],"class_list":["post-1136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-adolescentes","tag-embarazos","tag-la-semanal","tag-luis-abinader"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019 - Bombazo Informativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019 - Bombazo Informativo\" \/>\n<meta property=\"og:description\" content=\"Santo Domingo.-&nbsp;El presidente Luis Abinader&nbsp;resalt\u00f3 este lunes los logros alcanzados por el Gobierno,&nbsp;con respecto a la mujer, destacando que los&nbsp;embarazos en adolescentes&nbsp;pasaron de 32,061 en el a\u00f1o 2019 a&nbsp;23,070 en el a\u00f1o 2023. De igual modo, resalt\u00f3 que las exportaciones de&nbsp;empresas lideradas por mujeres&nbsp;desde el 2020 al 2023 superaron&nbsp;m\u00e1s de 7,295 millones de d\u00f3lares. Estas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Bombazo Informativo\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T15:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bombazo Informativo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bombazo Informativo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/\"},\"author\":{\"name\":\"Bombazo Informativo\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\"},\"headline\":\"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019\",\"datePublished\":\"2024-03-05T15:28:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/\"},\"wordCount\":682,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg\",\"keywords\":[\"Adolescentes\",\"Embarazos\",\"La Semanal\",\"Luis Abinader\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/\",\"name\":\"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019 - Bombazo Informativo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg\",\"datePublished\":\"2024-03-05T15:28:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#breadcrumb\"},\"inLanguage\":\"es-DO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg\",\"width\":1300,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/2024\\\/03\\\/05\\\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bombazoinformativo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#website\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"name\":\"Bombazo Informativo\",\"description\":\"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bombazoinformativo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-DO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#organization\",\"name\":\"Bombazo Informativo\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg\",\"width\":1599,\"height\":315,\"caption\":\"Bombazo Informativo\"},\"image\":{\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/#\\\/schema\\\/person\\\/8a14f30019ce669c2ff632f56c95babc\",\"name\":\"Bombazo Informativo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-DO\",\"@id\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"contentUrl\":\"https:\\\/\\\/bombazoinformativo.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045\",\"caption\":\"Bombazo Informativo\"},\"url\":\"https:\\\/\\\/bombazoinformativo.com\\\/index.php\\\/author\\\/bombazo-informativo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019 - Bombazo Informativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/","og_locale":"es_ES","og_type":"article","og_title":"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019 - Bombazo Informativo","og_description":"Santo Domingo.-&nbsp;El presidente Luis Abinader&nbsp;resalt\u00f3 este lunes los logros alcanzados por el Gobierno,&nbsp;con respecto a la mujer, destacando que los&nbsp;embarazos en adolescentes&nbsp;pasaron de 32,061 en el a\u00f1o 2019 a&nbsp;23,070 en el a\u00f1o 2023. De igual modo, resalt\u00f3 que las exportaciones de&nbsp;empresas lideradas por mujeres&nbsp;desde el 2020 al 2023 superaron&nbsp;m\u00e1s de 7,295 millones de d\u00f3lares. Estas...","og_url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/","og_site_name":"Bombazo Informativo","article_published_time":"2024-03-05T15:28:37+00:00","og_image":[{"width":1300,"height":731,"url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg","type":"image\/jpeg"}],"author":"Bombazo Informativo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bombazo Informativo","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#article","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/"},"author":{"name":"Bombazo Informativo","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc"},"headline":"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019","datePublished":"2024-03-05T15:28:37+00:00","mainEntityOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/"},"wordCount":682,"commentCount":0,"publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg","keywords":["Adolescentes","Embarazos","La Semanal","Luis Abinader"],"articleSection":["Nacionales"],"inLanguage":"es-DO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/","url":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/","name":"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019 - Bombazo Informativo","isPartOf":{"@id":"https:\/\/bombazoinformativo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#primaryimage"},"image":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg","datePublished":"2024-03-05T15:28:37+00:00","breadcrumb":{"@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#breadcrumb"},"inLanguage":"es-DO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#primaryimage","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg","width":1300,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/bombazoinformativo.com\/index.php\/2024\/03\/05\/abinader-embarazos-en-adolescentes-descienden-9000-casos-este-ano-en-comparacion-con-el-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bombazoinformativo.com\/"},{"@type":"ListItem","position":2,"name":"Abinader: Embarazos en adolescentes descienden 9,000 casos este a\u00f1o, en comparaci\u00f3n con el 2019"}]},{"@type":"WebSite","@id":"https:\/\/bombazoinformativo.com\/#website","url":"https:\/\/bombazoinformativo.com\/","name":"Bombazo Informativo","description":"En el Bombazo Informativo tenemos el objetivo de brindarte informaciones veraces, con claridad y objetividad.","publisher":{"@id":"https:\/\/bombazoinformativo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bombazoinformativo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-DO"},{"@type":"Organization","@id":"https:\/\/bombazoinformativo.com\/#organization","name":"Bombazo Informativo","url":"https:\/\/bombazoinformativo.com\/","logo":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/","url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/11\/cropped-WhatsApp-Image-2024-11-29-at-12.01.48-PM.jpeg","width":1599,"height":315,"caption":"Bombazo Informativo"},"image":{"@id":"https:\/\/bombazoinformativo.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bombazoinformativo.com\/#\/schema\/person\/8a14f30019ce669c2ff632f56c95babc","name":"Bombazo Informativo","image":{"@type":"ImageObject","inLanguage":"es-DO","@id":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","url":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","contentUrl":"https:\/\/bombazoinformativo.com\/wp-content\/litespeed\/avatar\/b076bbe918e43ad70d1f99495fbecd83.jpg?ver=1778472045","caption":"Bombazo Informativo"},"url":"https:\/\/bombazoinformativo.com\/index.php\/author\/bombazo-informativo\/"}]}},"jetpack_featured_media_url":"https:\/\/bombazoinformativo.com\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-04-at-7.49.20-PM.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1136"}],"version-history":[{"count":1,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1136\/revisions"}],"predecessor-version":[{"id":1138,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/1136\/revisions\/1138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media\/1137"}],"wp:attachment":[{"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bombazoinformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}